{"id":17584,"date":"2026-07-08T18:47:04","date_gmt":"2026-07-08T15:47:04","guid":{"rendered":"https:\/\/mcpmed-ti.edu.eu\/?post_type=courses&#038;p=17584"},"modified":"2026-07-08T16:47:19","modified_gmt":"2026-07-08T15:47:19","slug":"award-in-presentation-skills-essentials","status":"publish","type":"courses","link":"https:\/\/mcpmed-ti.edu.eu\/fr\/courses\/award-in-presentation-skills-essentials\/","title":{"rendered":"Prix des comp\u00e9tences essentielles en mati\u00e8re de pr\u00e9sentation"},"content":{"rendered":"<p>Le cours fournira aux participants les outils et les techniques n\u00e9cessaires pour pr\u00e9parer et pr\u00e9senter des expos\u00e9s et des discours percutants. Les participants apprendront \u00e0 pr\u00e9parer, planifier et structurer une pr\u00e9sentation, en mettant l'accent sur l'adaptation de leur message au public. Divers conseils et astuces pour capter l'attention de l'auditoire du d\u00e9but \u00e0 la fin seront pr\u00e9sent\u00e9s et mis en pratique. Certaines erreurs courantes commises par les orateurs seront \u00e9galement abord\u00e9es, dans le but de fournir des conseils pour les \u00e9viter et, le cas \u00e9ch\u00e9ant, pour s'en remettre. Des strat\u00e9gies efficaces pour g\u00e9rer les s\u00e9ances de questions-r\u00e9ponses seront \u00e9galement abord\u00e9es.<\/p>\n<p>Le programme utilise une approche d'apprentissage collaboratif et exp\u00e9rientiel. Gr\u00e2ce \u00e0 des exercices pratiques, au retour d'information et \u00e0 l'\u00e9valuation des pairs et des instructeurs, les participants acqui\u00e8rent une exp\u00e9rience pratique et d\u00e9veloppent leurs comp\u00e9tences en mati\u00e8re de pr\u00e9sentation afin d'obtenir un impact maximal dans des sc\u00e9narios de la vie r\u00e9elle.<\/p>\n<p><b>Accr\u00e9dit\u00e9 par la MFHEA<\/b><u><\/u>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<strong>Type de qualification :<\/strong> <span style=\"color: #3d4044\">Attestation<\/span><\/p>\n<p><strong>Cat\u00e9gorie d&#x27;accr\u00e9ditation :<\/strong> Formation continue \/ Programme<\/p>\n<p><strong>Sous licence MFHEA | Licence n\u00b0 : 2021-016<\/strong><\/p>\n<p><strong>ECTS:<\/strong> <span style=\"color: #3d4044\">1<\/span>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<strong>Dur\u00e9e de la formation :<\/strong> <span style=\"color: #3d4044\">4 jours<\/span><\/p>\n<p><b>Niveau MQF\/EQF :\u00a0<\/b>4<\/p>\n<p><strong>Mode de d\u00e9livrance\/pr\u00e9sence :<\/strong> <span style=\"color: #3d4044\">Face \u00e0 face\/temps plein<\/span><\/p>\n<p><strong>Heures de formation totale :<\/strong> <span style=\"color: #3d4044\">25 heures (contact : 17 heures\/auto-apprentissage : 2 heures\/\u00e9valuation : 6 heures)<\/span><\/p>\n<p><strong>Langue d'enseignement :<\/strong> <span style=\"color: #3d4044\">Anglais, fran\u00e7ais ou arabe<\/span><\/p>\n<p><strong>Adresse :<\/strong> Locaux agr\u00e9\u00e9s MCP Med TI<span style=\"color: #3d4044\">.<\/span><\/p>\n<p><strong>Modes d'enseignement<\/strong><\/p>\n<ul>\n<li><span style=\"color: #3d4044\">Conf\u00e9rence<\/span><\/li>\n<li><span style=\"color: #3d4044\">Aides visuelles<\/span><\/li>\n<li><span style=\"color: #3d4044\">Pl\u00e9ni\u00e8re\/discussions guid\u00e9es<\/span><\/li>\n<li><span style=\"color: #3d4044\">Exercices pratiques et en groupe<\/span><\/li>\n<li><span style=\"color: #3d4044\">\u00c9tudes de cas et jeux de r\u00f4le<\/span><\/li>\n<li><span style=\"color: #3d4044\">R\u00e9troaction des pairs et de l'instructeur<\/span><\/li>\n<li><span style=\"color: #3d4044\">Auto-apprentissage \u00e0 son rythme<\/span><\/li>\n<\/ul>\n<p><strong>\u00c9valuation<\/strong><\/p>\n<p>Pr\u00e9sence :<strong><br \/><\/strong><span style=\"color: #3d4044\">Une note compl\u00e8te implique une pr\u00e9sence sans interruption pendant toute la dur\u00e9e des \u00e9tudes.<\/span><\/p>\n<p>Note : <span style=\"color: #3d4044\">5 points<\/span><\/p>\n<p>L'application pratique est structur\u00e9e comme suit :<br \/><span style=\"color: #3d4044\">Les \u00e9tudiants devront participer, pendant toute la dur\u00e9e du cours, \u00e0 des discussions de groupe et \u00e0 des travaux en petits groupes. Les autres techniques utilis\u00e9es pour l'\u00e9valuation formative comprennent les techniques individuelles ou de groupe suivantes :<\/span><\/p>\n<ul>\n<li><span style=\"color: #3d4044\">Les \u00e9tudiants sont invit\u00e9s \u00e0 r\u00e9pondre aux questions pos\u00e9es par le formateur et d'autres \u00e9tudiants\/sous-groupes.<\/span><\/li>\n<li><span style=\"color: #3d4044\">R\u00e9capitulation du cours et session de questions-r\u00e9ponses (troisi\u00e8me jour de formation)<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #3d4044\">Une grille d'\u00e9valuation formative sera utilis\u00e9e afin (1) de soutenir des pratiques d'\u00e9valuation coh\u00e9rentes (2) de communiquer des attentes claires aux stagiaires, (3) d'assurer la transparence et (4) d'identifier les points forts et les domaines d'am\u00e9lioration.<\/span><\/p>\n<p>Note : <span style=\"color: #3d4044\">25 points<\/span><\/p>\n<p>Examen final :<br \/><span style=\"color: #3d4044\">L'examen final est divis\u00e9 en deux parties :<\/span><\/p>\n<ol>\n<li><strong>Premi\u00e8re partie :<\/strong><br \/>Composante \u00e9crite : <span style=\"color: #3d4044\">Test \u00e0 choix multiples comprenant 10 questions<\/span><br \/>Note : <span style=\"color: #3d4044\">20 points<\/span><br \/>Temps consacr\u00e9 : <span style=\"color: #3d4044\">45 minutes<\/span><br \/><b>Exemple de question :\u00a0<\/b><span style=\"color: #3d4044\"><span style=\"font-weight: 400\">Lequel des \u00e9l\u00e9ments suivants est une structure de pr\u00e9sentation qui vise \u00e0 <\/span><b>persuader l'auditoire d'accepter une solution propos\u00e9e<\/b><span style=\"font-weight: 400\">:\u00a0<\/span><\/span>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"color: #3d4044\">Captiver-d\u00e9velopper-tirer<\/span><\/li>\n<li><span style=\"color: #3d4044\">Probl\u00e8me-solution-b\u00e9n\u00e9fice<\/span><\/li>\n<li><span style=\"color: #3d4044\">Probl\u00e8me-b\u00e9n\u00e9fice-solution<\/span><\/li>\n<li><span style=\"color: #3d4044\">D\u00e9velopper-captiver-tirer<\/span><\/li>\n<\/ul>\n<\/li>\n<li><strong>Partie 2 :<br \/><\/strong>Composante pratique : <span style=\"color: #3d4044\">Pr\u00e9paration et pr\u00e9sentation d'un expos\u00e9 de 5 minutes (individuel)<\/span><br \/>Note : <span style=\"color: #3d4044\">50 points<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;color: #3d4044\">Pour la composante pratique, le formateur \u00e9valuera les participants \u00e0 l'aide des cat\u00e9gories suivantes et de leur pond\u00e9ration respective. Les cat\u00e9gories sont d\u00e9finies comme suit :\u00a0<\/span><\/p>\n<p><b>Contenu (25%) :<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Clart\u00e9 et pertinence du message principal.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Organisation efficace et encha\u00eenement logique des id\u00e9es.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Connaissance du sujet<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Qualit\u00e9 et pr\u00e9cision des preuves et exemples \u00e0 l'appui (le cas \u00e9ch\u00e9ant).<\/span><\/li>\n<\/ul>\n<p><b>Livraison (25%) :<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Une pr\u00e9sence engageante et confiante<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Langage corporel, gestes et contact visuel appropri\u00e9s<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Projection vocale, rythme et modulation pour maintenir l'int\u00e9r\u00eat de l'auditoire<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Utilisation efficace d'aides visuelles et d'autres supports (le cas \u00e9ch\u00e9ant)\u00a0<\/span><\/li>\n<\/ul>\n<p><b>Connexion avec le public (15%) :<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Capacit\u00e9 \u00e0 \u00e9tablir une relation et \u00e0 se connecter avec le public.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Engagement et r\u00e9activit\u00e9 face aux r\u00e9actions du public.<\/span><\/li>\n<\/ul>\n<p><b>Gestion du temps (10 %) :<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Respecter le temps imparti de 5 minutes.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Utilisation efficace du temps pour couvrir tous les points essentiels.<\/span><\/li>\n<\/ul>\n<p><b>S\u00e9ance de questions-r\u00e9ponses (10 %)\u00a0<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Traitement habile des questions\u00a0<\/span><\/li>\n<\/ul>\n<p><b>Impact global (15 %) :<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Style de pr\u00e9sentation m\u00e9morable et percutant (y compris au d\u00e9but et \u00e0 la fin du discours)\u00a0<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Persuasion et capacit\u00e9 \u00e0 inspirer l'action.<\/span><\/li>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400;color: #3d4044\">Originalit\u00e9 et cr\u00e9ativit\u00e9 dans la transmission des id\u00e9es.<\/span><\/li>\n<\/ul>\n<p>Note : <span style=\"color: #3d4044\">70 points<\/span><\/p>\n<p><span style=\"color: #3d4044\">La note de passage pour la r\u00e9ussite du programme : 60\/100<\/span><\/p>\n<p><strong>Informations compl\u00e9mentaires :<\/strong><\/p>\n<ul>\n<li><span style=\"color: #3d4044\">Dates d'admission : <span class=\"rnc2Gd\" data-ast-node-id=\"23\">Pas de dates d'inscription fixes. Ce programme est dispens\u00e9 sur demande et planifi\u00e9 en coop\u00e9ration avec les institutions partenaires et les autorit\u00e9s nationales. Veuillez contacter\u00a0<\/span><a href=\"mailto:mcpmedti@icmpd.org\" target=\"_blank\" rel=\"noopener noreferrer\"><span class=\"rnc2Gd\" data-ast-node-id=\"24\">mcpmedti@icmpd.org<\/span><\/a><span class=\"rnc2Gd\" data-ast-node-id=\"25\">\u00a0pour des informations sur les livraisons \u00e0 venir.<\/span><\/span><\/li>\n<li><span style=\"color: #3d4044\">Frais d'inscription : Il n'y a pas de frais de scolarit\u00e9 standard. La participation est gratuite pour les participants d\u00e9sign\u00e9s des institutions publiques \u00e9ligibles, conform\u00e9ment aux accords et communications applicables avec MCP Med TI. Pour plus d'informations, veuillez contacter\u00a0<a href=\"mailto:mcpmedti@icmpd.org\" target=\"_blank\" rel=\"noopener\">mcpmedti@icmpd.org<\/a>.<\/span><\/li>\n<li><span style=\"color: #3d4044\">Mode d'inscription : <span class=\"rnc2Gd\" data-ast-node-id=\"19\">L'inscription n'est pas ouverte au grand public. Les participants sont d\u00e9sign\u00e9s par les institutions partenaires ou les autorit\u00e9s nationales comp\u00e9tentes. Les organisations int\u00e9ress\u00e9es par la prestation de ce programme peuvent contacter\u00a0<\/span><a href=\"mailto:mcpmedti@icmpd.org\" target=\"_blank\" rel=\"noopener noreferrer\"><span class=\"rnc2Gd\" data-ast-node-id=\"20\">mcpmedti@icmpd.org<\/span><\/a><span class=\"rnc2Gd\" data-ast-node-id=\"21\">.<\/span><\/span><\/li>\n<\/ul>\n<p><strong>Exigences de visa :<\/strong><\/p>\n<p>Les ressortissants de pays tiers qui participent \u00e0 ce programme \u00e0 Malte doivent consulter Identity Malta pour conna\u00eetre les exigences en mati\u00e8re de visa :\u00a0<a href=\"https:\/\/www.identitymalta.com\/unit\/central-visa-unit\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.identitymalta.com\/unit\/central-visa-unit\/&amp;source=gmail&amp;ust=1783085145040000&amp;usg=AOvVaw0uHhoLeuQPVqvjA2UJnDPS\">https:\/\/www.identitymalta.com\/<wbr \/>unit\u00e9\/central-visa-unit\u00e9\/<\/a><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-19706\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2021\/11\/MQF-Logo-Proposal.png\" alt=\"\" width=\"120\" height=\"85\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2021\/11\/MQF-Logo-Proposal.png 1080w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2021\/11\/MQF-Logo-Proposal-300x213.png 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2021\/11\/MQF-Logo-Proposal-1024x725.png 1024w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2021\/11\/MQF-Logo-Proposal-768x544.png 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2021\/11\/MQF-Logo-Proposal-18x12.png 18w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>The course will equip participants with the required tools and techniques to prepare and deliver impactful presentations and speeches. Participants will learn how to prepare, plan and structure a presentation, with an emphasis on tailoring their message to the audience. Various tips and tricks for engaging the audience from start to finish will be featured&#8230;<\/p>","protected":false},"author":1,"featured_media":17610,"template":"","tutor_course_language":[131],"course-category":[174],"course-tag":[199,200],"class_list":["post-17584","courses","type-courses","status-publish","has-post-thumbnail","hentry","tutor_course_language-english","course-category-professional-development","course-tag-face-to-face-accredited","course-tag-professional-development"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Award in Presentation Skills Essentials - MCP Med TI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/courses\/award-in-presentation-skills-essentials\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Award in Presentation Skills Essentials\" \/>\n<meta property=\"og:description\" content=\"The course will equip participants with the required tools and techniques to prepare and deliver impactful presentations and speeches. Participants will learn how to prepare, plan and structure a presentation, with an emphasis on tailoring their message to the audience. Various tips and tricks for engaging the audience from start to finish will be featured&#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mcpmed-ti.edu.eu\/fr\/courses\/award-in-presentation-skills-essentials\/\" \/>\n<meta property=\"og:site_name\" content=\"MCP Med TI\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T15:47:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/08\/Award-in-Presentation-Skills-Essentials-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-presentation-skills-essentials\\\/\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-presentation-skills-essentials\\\/\",\"name\":\"Award in Presentation Skills Essentials - MCP Med TI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-presentation-skills-essentials\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-presentation-skills-essentials\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Award-in-Presentation-Skills-Essentials-1.jpg\",\"datePublished\":\"2026-07-08T15:47:04+00:00\",\"dateModified\":\"2026-07-08T15:47:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-presentation-skills-essentials\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-presentation-skills-essentials\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-presentation-skills-essentials\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Award-in-Presentation-Skills-Essentials-1.jpg\",\"contentUrl\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Award-in-Presentation-Skills-Essentials-1.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-presentation-skills-essentials\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Courses\",\"item\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Award in Presentation Skills Essentials\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#website\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/\",\"name\":\"MCP Med TI\",\"description\":\"MCP Med TI\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#organization\",\"name\":\"MCP Med Training Institute\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-cropped-256px_MCPMedTI-1.png\",\"contentUrl\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-cropped-256px_MCPMedTI-1.png\",\"width\":512,\"height\":512,\"caption\":\"MCP Med Training Institute\"},\"image\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/linkedin.com\\\/company\\\/mcpmedti\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Award in Presentation Skills Essentials - MCP Med TI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mcpmed-ti.edu.eu\/fr\/courses\/award-in-presentation-skills-essentials\/","og_locale":"fr_FR","og_type":"article","og_title":"Award in Presentation Skills Essentials","og_description":"The course will equip participants with the required tools and techniques to prepare and deliver impactful presentations and speeches. Participants will learn how to prepare, plan and structure a presentation, with an emphasis on tailoring their message to the audience. Various tips and tricks for engaging the audience from start to finish will be featured&#8230;","og_url":"https:\/\/mcpmed-ti.edu.eu\/fr\/courses\/award-in-presentation-skills-essentials\/","og_site_name":"MCP Med TI","article_modified_time":"2026-07-08T15:47:19+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/08\/Award-in-Presentation-Skills-Essentials-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-presentation-skills-essentials\/","url":"https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-presentation-skills-essentials\/","name":"Award in Presentation Skills Essentials - MCP Med TI","isPartOf":{"@id":"https:\/\/mcpmed-ti.edu.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-presentation-skills-essentials\/#primaryimage"},"image":{"@id":"https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-presentation-skills-essentials\/#primaryimage"},"thumbnailUrl":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/08\/Award-in-Presentation-Skills-Essentials-1.jpg","datePublished":"2026-07-08T15:47:04+00:00","dateModified":"2026-07-08T15:47:19+00:00","breadcrumb":{"@id":"https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-presentation-skills-essentials\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-presentation-skills-essentials\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-presentation-skills-essentials\/#primaryimage","url":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/08\/Award-in-Presentation-Skills-Essentials-1.jpg","contentUrl":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/08\/Award-in-Presentation-Skills-Essentials-1.jpg","width":1200,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-presentation-skills-essentials\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mcpmed-ti.edu.eu\/"},{"@type":"ListItem","position":2,"name":"Courses","item":"https:\/\/mcpmed-ti.edu.eu\/courses\/"},{"@type":"ListItem","position":3,"name":"Award in Presentation Skills Essentials"}]},{"@type":"WebSite","@id":"https:\/\/mcpmed-ti.edu.eu\/#website","url":"https:\/\/mcpmed-ti.edu.eu\/","name":"MCP Med TI","description":"MCP Med TI","publisher":{"@id":"https:\/\/mcpmed-ti.edu.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mcpmed-ti.edu.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mcpmed-ti.edu.eu\/#organization","name":"Institut de formation m\u00e9dicale MCP","url":"https:\/\/mcpmed-ti.edu.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mcpmed-ti.edu.eu\/#\/schema\/logo\/image\/","url":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI-1.png","contentUrl":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI-1.png","width":512,"height":512,"caption":"MCP Med Training Institute"},"image":{"@id":"https:\/\/mcpmed-ti.edu.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/linkedin.com\/company\/mcpmedti"]}]}},"_links":{"self":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/courses\/17584","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/courses"}],"about":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/types\/courses"}],"author":[{"embeddable":true,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/courses\/17584\/revisions"}],"predecessor-version":[{"id":20276,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/courses\/17584\/revisions\/20276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/media\/17610"}],"wp:attachment":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/media?parent=17584"}],"wp:term":[{"taxonomy":"tutor_course_language","embeddable":true,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/tutor_course_language?post=17584"},{"taxonomy":"course-category","embeddable":true,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/course-category?post=17584"},{"taxonomy":"course-tag","embeddable":true,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/course-tag?post=17584"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}