{"id":18228,"date":"2026-08-03T17:11:05","date_gmt":"2026-08-03T14:11:05","guid":{"rendered":"https:\/\/mcpmed-ti.edu.eu\/?post_type=courses&#038;p=18228"},"modified":"2026-08-03T15:11:15","modified_gmt":"2026-08-03T14:11:15","slug":"award-in-introduction-to-transnational-organised-crime","status":"publish","type":"courses","link":"https:\/\/mcpmed-ti.edu.eu\/fr\/courses\/award-in-introduction-to-transnational-organised-crime\/","title":{"rendered":"Certificat d'introduction \u00e0 la criminalit\u00e9 transnationale organis\u00e9e"},"content":{"rendered":"<p><span style=\"color: #3d4044\">Ce programme de formation dynamique et intensif est con\u00e7u pour les praticiens de la migration de premi\u00e8re ligne, en particulier ceux d\u00e9ploy\u00e9s aux fronti\u00e8res et activement engag\u00e9s dans la lutte contre la criminalit\u00e9 transnationale organis\u00e9e. Pendant quatre jours de formation cons\u00e9cutifs (25 heures d'apprentissage), les apprenants acquerront une compr\u00e9hension approfondie des concepts fondamentaux de la criminalit\u00e9 transnationale organis\u00e9e, de ses diff\u00e9rentes formes et du r\u00f4le essentiel des premiers intervenants. Ils approfondiront les concepts fondamentaux et les cadres juridiques de la criminalit\u00e9 organis\u00e9e, en explorant des domaines cl\u00e9s tels que la traite des \u00eatres humains, le trafic de migrants, le trafic de stup\u00e9fiants et le blanchiment d'argent. Le programme met l'accent sur l'identification des \u00ab signaux d'alarme \u00bb et sur l'importance cruciale de la collecte et de la pr\u00e9servation des preuves, en donnant aux premiers intervenants les moyens de soutenir efficacement les enqu\u00eates.<\/span><br \/><span style=\"color: #3d4044\">La formation souligne \u00e9galement l'importance vitale de la coop\u00e9ration internationale dans la lutte contre le COT, en dotant les apprenants des outils et des strat\u00e9gies n\u00e9cessaires \u00e0 une collaboration efficace avec des partenaires mondiaux.<\/span><\/p>\n<p><b>Accr\u00e9dit\u00e9 par la MFHEA<\/b><u><\/u>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<strong>Type de qualification :<\/strong>\u00a0Attestation<\/p>\n<p><strong>Cat\u00e9gorie d&#x27;accr\u00e9ditation :<\/strong>\u00a0Formation continue \/ Programme<\/p>\n<p><strong>Sous licence MFHEA | Licence n\u00b0 : 2021-016<\/strong><\/p>\n<p><strong>ECTS:<\/strong> <span style=\"color: #3d4044\">1<\/span>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0<strong>Dur\u00e9e de la formation :<\/strong> <span style=\"color: #3d4044\">4 jours<\/span><\/p>\n<p><b>Niveau MQF\/EQF :\u00a0<\/b>4<\/p>\n<p><strong>Mode de d\u00e9livrance\/pr\u00e9sence :<\/strong> <span style=\"color: #3d4044\">Face \u00e0 face\/temps plein<\/span><\/p>\n<p><strong>Heures de formation totale :<\/strong> <span style=\"color: #3d4044\">25 heures (contact : 21 heures\/auto-apprentissage : 2 heures\/\u00e9valuation : 2 heures)<\/span><\/p>\n<p><strong>Langue d'enseignement :<\/strong> <span style=\"color: #3d4044\">Anglais, fran\u00e7ais ou arabe<\/span><\/p>\n<p><strong>Adresse :<\/strong> Locaux agr\u00e9\u00e9s MCP Med TI<span style=\"color: #3d4044\">.<\/span><\/p>\n<p><strong>Modes d'enseignement<\/strong><\/p>\n<ul>\n<li><span style=\"color: #3d4044\">Conf\u00e9rences<\/span><\/li>\n<li><span style=\"color: #3d4044\">Aides visuelles<\/span><\/li>\n<li><span style=\"color: #3d4044\">Pl\u00e9ni\u00e8re\/discussions guid\u00e9es<\/span><\/li>\n<li><span style=\"color: #3d4044\">Exercices pratiques et en groupe<\/span><\/li>\n<li><span style=\"color: #3d4044\">\u00c9tudes de cas<\/span><\/li>\n<li><span style=\"color: #3d4044\">Auto-apprentissage \u00e0 son rythme<\/span><\/li>\n<\/ul>\n<p><strong>\u00c9valuation<\/strong><\/p>\n<p>Pr\u00e9sence :<strong><br \/><\/strong><span style=\"color: #3d4044\">Une note compl\u00e8te implique une pr\u00e9sence sans interruption pendant toute la dur\u00e9e des \u00e9tudes.<\/span><\/p>\n<p>Note : <span style=\"color: #3d4044\">5 points<\/span><\/p>\n<p>\u00c9valuation formative :<br \/><span style=\"color: #3d4044\">Les techniques d'\u00e9valuation formative engloberont \u00e0 la fois des approches individuelles et de groupe. Les apprenants devront participer tout au long du cours \u00e0 une vari\u00e9t\u00e9 de discussions de groupe\/guid\u00e9es, de s\u00e9ances de questions-r\u00e9ponses, d'exercices pratiques, d'\u00e9tudes de cas et de travaux en petits groupes.<\/span><\/p>\n<p>Note : <span style=\"color: #3d4044\">35 points<\/span><\/p>\n<p>Examen final :<br \/><span style=\"color: #3d4044\">L'examen final est con\u00e7u pour \u00e9valuer la compr\u00e9hension des apprenants des concepts abord\u00e9s pendant le cours et leur aptitude \u00e0 les appliquer \u00e0 des sc\u00e9narios pratiques. Les questions comprennent un m\u00e9lange vari\u00e9 de choix multiples, de vrai ou faux et de texte narratif libre (formats \u00e0 r\u00e9ponse courte) - (20 questions au total).<\/span><\/p>\n<p><u>Exemple de question : <\/u><\/p>\n<p><span style=\"color: #3d4044\"><em>Lequel des \u00e9l\u00e9ments suivants est un exemple de criminalit\u00e9 transnationale selon la Convention des Nations Unies sur la lutte contre la criminalit\u00e9 transnationale organis\u00e9e (UNTOC) ?<\/em><\/span><\/p>\n<ol>\n<li><span style=\"color: #3d4044\"><em>Un groupe de 6 policiers de la gendarmerie fran\u00e7aise organise et ex\u00e9cute 30 braquages de banques sur une p\u00e9riode de 7 ans dans diff\u00e9rentes r\u00e9gions de France. <\/em><\/span><\/li>\n<li><span style=\"color: #3d4044\"><em>Une entreprise chimique, avec l'aide d'un groupe criminel organis\u00e9, d\u00e9verse des d\u00e9chets toxiques dans le Danube \u00e0 la p\u00e9riph\u00e9rie de Bratislava, en Slovaquie, ce qui entra\u00eene une s\u00e9rie de pollutions des terres agricoles et des p\u00eacheries dans la Hongrie voisine.<\/em><\/span><\/li>\n<li><span style=\"color: #3d4044\"><em>Un militant norv\u00e9gien de la lutte contre le changement climatique assassine le pr\u00e9sident d'une compagnie p\u00e9troli\u00e8re \u00e0 Oslo, en Norv\u00e8ge.<\/em><\/span><\/li>\n<\/ol>\n<p><span style=\"color: #3d4044\"><em><strong>Remarque importante :<\/strong> les exemples de questions ci-dessus servent \u00e0 donner une premi\u00e8re id\u00e9e du type de questions qui peuvent \u00eatre pos\u00e9es et peuvent \u00eatre r\u00e9examin\u00e9es \u00e0 un stade ult\u00e9rieur.<\/em><\/span><\/p>\n<p>Note : <span style=\"color: #3d4044\">60 points<\/span><\/p>\n<p><span style=\"color: #3d4044\">La note de passage pour la r\u00e9ussite du programme : 60\/100<\/span><\/p>\n<p><strong>Informations compl\u00e9mentaires :<\/strong><\/p>\n<ul>\n<li><span style=\"color: #3d4044\">Dates d'admission : <span class=\"rnc2Gd\" data-ast-node-id=\"23\">Pas de dates d'inscription fixes. Ce programme est dispens\u00e9 sur demande et planifi\u00e9 en coop\u00e9ration avec les institutions partenaires et les autorit\u00e9s nationales. Veuillez contacter\u00a0<\/span><a href=\"mailto:mcpmedti@icmpd.org\" target=\"_blank\" rel=\"noopener noreferrer\"><span class=\"rnc2Gd\" data-ast-node-id=\"24\">mcpmedti@icmpd.org<\/span><\/a><span class=\"rnc2Gd\" data-ast-node-id=\"25\">\u00a0pour des informations sur les livraisons \u00e0 venir.<\/span><\/span><\/li>\n<li><span style=\"color: #3d4044\">Frais d'inscription : Il n'y a pas de frais de scolarit\u00e9 standard. La participation est gratuite pour les participants d\u00e9sign\u00e9s des institutions publiques \u00e9ligibles, conform\u00e9ment aux accords et communications applicables avec MCP Med TI. Pour plus d'informations, veuillez contacter\u00a0<a href=\"mailto:mcpmedti@icmpd.org\" target=\"_blank\" rel=\"noopener\">mcpmedti@icmpd.org<\/a>.<\/span><\/li>\n<li><span style=\"color: #3d4044\">M\u00e9thode d'inscription : L'inscription n'est actuellement pas ouverte au grand public<span class=\"rnc2Gd\" data-ast-node-id=\"19\">. Les participants sont nomm\u00e9s par les institutions partenaires ou les autorit\u00e9s nationales comp\u00e9tentes. Les organisations int\u00e9ress\u00e9es par la mise en \u0153uvre de ce programme peuvent contacter\u00a0<\/span><a href=\"mailto:mcpmedti@icmpd.org\" target=\"_blank\" rel=\"noopener noreferrer\"><span class=\"rnc2Gd\" data-ast-node-id=\"20\">mcpmedti@icmpd.org<\/span><\/a><span class=\"rnc2Gd\" data-ast-node-id=\"21\">.<\/span><\/span><\/li>\n<\/ul>\n<p><strong>Exigences de visa :<\/strong><\/p>\n<p>Les ressortissants de pays tiers qui participent \u00e0 ce programme \u00e0 Malte doivent consulter Identity Malta pour conna\u00eetre les exigences en mati\u00e8re de visa :\u00a0<a href=\"https:\/\/www.identitymalta.com\/unit\/central-visa-unit\/\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.identitymalta.com\/unit\/central-visa-unit\/&amp;source=gmail&amp;ust=1783085145040000&amp;usg=AOvVaw0uHhoLeuQPVqvjA2UJnDPS\">https:\/\/www.identitymalta.com\/<wbr \/>unit\u00e9\/central-visa-unit\u00e9\/<\/a><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-19706\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2021\/11\/MQF-Logo-Proposal.png\" alt=\"\" width=\"120\" height=\"85\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2021\/11\/MQF-Logo-Proposal.png 1080w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2021\/11\/MQF-Logo-Proposal-300x213.png 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2021\/11\/MQF-Logo-Proposal-1024x725.png 1024w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2021\/11\/MQF-Logo-Proposal-768x544.png 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2021\/11\/MQF-Logo-Proposal-18x12.png 18w\" sizes=\"(max-width: 120px) 100vw, 120px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>This dynamic and intensive training programme is designed for 1st line migration practitioners, particularly those deployed at the border and actively engaged in the fight against Transnational Organised Crime. Over four consecutive training days (25 hours of learning), learners will gain a deep understanding of foundational TOC concepts, its various forms, and the pivotal role&#8230;<\/p>","protected":false},"author":1,"featured_media":18707,"template":"","tutor_course_language":[131],"course-category":[6],"course-tag":[199],"class_list":["post-18228","courses","type-courses","status-publish","has-post-thumbnail","hentry","tutor_course_language-english","course-category-border-management-and-security","course-tag-face-to-face-accredited"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Award in Introduction to Transnational Organised Crime - MCP Med TI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/courses\/award-in-introduction-to-transnational-organised-crime\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Award in Introduction to Transnational Organised Crime\" \/>\n<meta property=\"og:description\" content=\"This dynamic and intensive training programme is designed for 1st line migration practitioners, particularly those deployed at the border and actively engaged in the fight against Transnational Organised Crime. Over four consecutive training days (25 hours of learning), learners will gain a deep understanding of foundational TOC concepts, its various forms, and the pivotal role&#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mcpmed-ti.edu.eu\/fr\/courses\/award-in-introduction-to-transnational-organised-crime\/\" \/>\n<meta property=\"og:site_name\" content=\"MCP Med TI\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-03T14:11:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/01\/organized-crime.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"819\" \/>\n\t<meta property=\"og:image:height\" content=\"546\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-introduction-to-transnational-organised-crime\\\/\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-introduction-to-transnational-organised-crime\\\/\",\"name\":\"Award in Introduction to Transnational Organised Crime - MCP Med TI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-introduction-to-transnational-organised-crime\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-introduction-to-transnational-organised-crime\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/organized-crime.jpg\",\"datePublished\":\"2026-08-03T14:11:05+00:00\",\"dateModified\":\"2026-08-03T14:11:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-introduction-to-transnational-organised-crime\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-introduction-to-transnational-organised-crime\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-introduction-to-transnational-organised-crime\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/organized-crime.jpg\",\"contentUrl\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/organized-crime.jpg\",\"width\":819,\"height\":546},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/award-in-introduction-to-transnational-organised-crime\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Courses\",\"item\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/courses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Award in Introduction to Transnational Organised Crime\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#website\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/\",\"name\":\"MCP Med TI\",\"description\":\"MCP Med TI\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#organization\",\"name\":\"MCP Med Training Institute\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-cropped-256px_MCPMedTI-1.png\",\"contentUrl\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-cropped-256px_MCPMedTI-1.png\",\"width\":512,\"height\":512,\"caption\":\"MCP Med Training Institute\"},\"image\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/linkedin.com\\\/company\\\/mcpmedti\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Award in Introduction to Transnational Organised Crime - MCP Med TI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mcpmed-ti.edu.eu\/fr\/courses\/award-in-introduction-to-transnational-organised-crime\/","og_locale":"fr_FR","og_type":"article","og_title":"Award in Introduction to Transnational Organised Crime","og_description":"This dynamic and intensive training programme is designed for 1st line migration practitioners, particularly those deployed at the border and actively engaged in the fight against Transnational Organised Crime. Over four consecutive training days (25 hours of learning), learners will gain a deep understanding of foundational TOC concepts, its various forms, and the pivotal role&#8230;","og_url":"https:\/\/mcpmed-ti.edu.eu\/fr\/courses\/award-in-introduction-to-transnational-organised-crime\/","og_site_name":"MCP Med TI","article_modified_time":"2026-08-03T14:11:15+00:00","og_image":[{"width":819,"height":546,"url":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/01\/organized-crime.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-introduction-to-transnational-organised-crime\/","url":"https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-introduction-to-transnational-organised-crime\/","name":"Award in Introduction to Transnational Organised Crime - MCP Med TI","isPartOf":{"@id":"https:\/\/mcpmed-ti.edu.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-introduction-to-transnational-organised-crime\/#primaryimage"},"image":{"@id":"https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-introduction-to-transnational-organised-crime\/#primaryimage"},"thumbnailUrl":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/01\/organized-crime.jpg","datePublished":"2026-08-03T14:11:05+00:00","dateModified":"2026-08-03T14:11:15+00:00","breadcrumb":{"@id":"https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-introduction-to-transnational-organised-crime\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-introduction-to-transnational-organised-crime\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-introduction-to-transnational-organised-crime\/#primaryimage","url":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/01\/organized-crime.jpg","contentUrl":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/01\/organized-crime.jpg","width":819,"height":546},{"@type":"BreadcrumbList","@id":"https:\/\/mcpmed-ti.edu.eu\/courses\/award-in-introduction-to-transnational-organised-crime\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mcpmed-ti.edu.eu\/"},{"@type":"ListItem","position":2,"name":"Courses","item":"https:\/\/mcpmed-ti.edu.eu\/courses\/"},{"@type":"ListItem","position":3,"name":"Award in Introduction to Transnational Organised Crime"}]},{"@type":"WebSite","@id":"https:\/\/mcpmed-ti.edu.eu\/#website","url":"https:\/\/mcpmed-ti.edu.eu\/","name":"MCP Med TI","description":"MCP Med TI","publisher":{"@id":"https:\/\/mcpmed-ti.edu.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mcpmed-ti.edu.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mcpmed-ti.edu.eu\/#organization","name":"Institut de formation m\u00e9dicale MCP","url":"https:\/\/mcpmed-ti.edu.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mcpmed-ti.edu.eu\/#\/schema\/logo\/image\/","url":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI-1.png","contentUrl":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI-1.png","width":512,"height":512,"caption":"MCP Med Training Institute"},"image":{"@id":"https:\/\/mcpmed-ti.edu.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/linkedin.com\/company\/mcpmedti"]}]}},"_links":{"self":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/courses\/18228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/courses"}],"about":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/types\/courses"}],"author":[{"embeddable":true,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":10,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/courses\/18228\/revisions"}],"predecessor-version":[{"id":20367,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/courses\/18228\/revisions\/20367"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/media\/18707"}],"wp:attachment":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/media?parent=18228"}],"wp:term":[{"taxonomy":"tutor_course_language","embeddable":true,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/tutor_course_language?post=18228"},{"taxonomy":"course-category","embeddable":true,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/course-category?post=18228"},{"taxonomy":"course-tag","embeddable":true,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/course-tag?post=18228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}