{"id":774,"date":"2019-04-05T05:26:19","date_gmt":"2019-04-05T05:26:19","guid":{"rendered":"http:\/\/zetheme.com\/wordpress\/edubin\/?page_id=774"},"modified":"2026-08-03T14:50:41","modified_gmt":"2026-08-03T13:50:41","slug":"home","status":"publish","type":"page","link":"https:\/\/mcpmed-ti.edu.eu\/fr\/","title":{"rendered":"Accueil"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"774\" class=\"elementor elementor-774\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9bb9b05 elementor-section-stretched elementor-section-full_width elementor-section-height-min-height elementor-section-height-default elementor-section-items-middle\" data-id=\"9bb9b05\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/ICMPD-HQ.mp4&quot;,&quot;background_play_on_mobile&quot;:&quot;yes&quot;,&quot;background_video_start&quot;:9}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" role=\"presentation\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5f542cb\" data-id=\"5f542cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe39672 elementor-widget elementor-widget-custom-title-addons\" data-id=\"fe39672\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"custom-title-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tpc-double_heading\"><div class=\"dbl__subtitle\"><span>Bienvenue sur le site de<\/span><\/div><h1 class=\"dbl__title-wrapper\"><span class=\"dbl__title dbl-title_1\">MCP MED<br>Institut de formation<\/span><\/h1><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1cffd37 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1cffd37\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ccfbdd9\" data-id=\"ccfbdd9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78e82c2 edubin-title-align-left elementor-invisible elementor-widget elementor-widget-section-title-addons\" data-id=\"78e82c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"section-title-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"edubin-section-title edubin-subtitle-position- title-style-four\">\r\n                <h2 class=\"section-title-txt\">Qui nous sommes<\/h2><div class=\"edubin-title-sperator-sec\"><span class=\"edubin-title-sperator\">&nbsp;<\/span><\/div>            <\/div>\r\n\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b4fe3a6 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"b4fe3a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019Institut de formation sur le Partenariat pour les Capacit\u00e9s Migratoires en M\u00e9diterran\u00e9e (MCP Med Training Institute) est un centre d'excellence professionnelle sp\u00e9cifique \u00e0 la gouvernance des migrations, un projet mis en \u0153uvre par <a href=\"https:\/\/www.icmpd.org\/\">ICMPD<\/a>. Il s'agit d'un prestataire de formation multith\u00e9matique pour les \u00c9tats m\u00e9diterran\u00e9ens partenaires du Sud non membres de l'UE. Situ\u00e9 \u00e0 Malte, il dispose d'installations agr\u00e9\u00e9es dans toute la M\u00e9diterran\u00e9e, d'un vaste r\u00e9seau de formateurs agr\u00e9\u00e9s et de cours sanctionn\u00e9s par des qualifications reconnues au niveau europ\u00e9en.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-09f9497 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"09f9497\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b587f3\" data-id=\"8b587f3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5ace65b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ace65b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-3d12d9d elementor-invisible\" data-id=\"3d12d9d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3448f8 edubin-title-align-left elementor-widget elementor-widget-section-title-addons\" data-id=\"a3448f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"section-title-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"edubin-section-title edubin-subtitle-position-top title-style-four\">\r\n                <h2 class=\"section-title-txt\">Points forts de l'institut de formation MCP Med<\/h2><div class=\"edubin-title-sperator-sec\"><span class=\"edubin-title-sperator\">&nbsp;<\/span><\/div><p class=\"section-subtitle-txt\">Ce que nous offrons<\/p>            <\/div>\r\n\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dca6da6 elementor-vertical-align-middle elementor-position-left elementor-widget elementor-widget-image-box\" data-id=\"dca6da6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img fetchpriority=\"high\" decoding=\"async\" width=\"256\" height=\"256\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2019\/08\/034-ebook.png\" class=\"attachment-medium_large size-medium_large wp-image-4057\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2019\/08\/034-ebook.png 256w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2019\/08\/034-ebook-150x150.png 150w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2019\/08\/034-ebook-100x100.png 100w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/><\/figure><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\">Promouvoir la professionnalisation dans la r\u00e9gion<\/div><p class=\"elementor-image-box-description\">Un institut de formation pr\u00e9sent dans 17 pays avec 158 formateurs agr\u00e9\u00e9s.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c188d3 elementor-vertical-align-middle elementor-position-left elementor-widget elementor-widget-image-box\" data-id=\"9c188d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2019\/08\/015-answer.png\" title=\"015-r\u00e9ponse\" alt=\"015-answer\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\">Cours accr\u00e9dit\u00e9s par l'UE<\/div><p class=\"elementor-image-box-description\">Le MCP MED Training Institute est officiellement agr\u00e9\u00e9 en tant qu'\u00e9tablissement d'enseignement sup\u00e9rieur de l'UE par la MFHEA, actuellement autoris\u00e9 \u00e0 dispenser et \u00e0 d\u00e9livrer des qualifications de l'UE pour les cours accr\u00e9dit\u00e9s jusqu'au niveau 4 du cadre europ\u00e9en des certifications, agr\u00e9\u00e9s \u00e0 Malte.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e2f308 elementor-vertical-align-middle elementor-position-left elementor-widget elementor-widget-image-box\" data-id=\"0e2f308\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2019\/08\/055-contract-11.png\" title=\"055-contrat-11\" alt=\"055-contract-11\" loading=\"lazy\" \/><\/figure><div class=\"elementor-image-box-content\"><div class=\"elementor-image-box-title\">Renforcer les dialogues et les r\u00e9seaux dans la r\u00e9gion<\/div><p class=\"elementor-image-box-description\">Le MCP MED Training Institute cr\u00e9e un espace d'apprentissage entre pairs, de mentorat et de promotion de partenariats bas\u00e9s sur la confiance dans toute la r\u00e9gion.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5c1b54e elementor-invisible\" data-id=\"5c1b54e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;slideInLeft&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-00e1fc0 elementor-widget elementor-widget-image\" data-id=\"00e1fc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/07\/MINIMALISTIC-MAP-2026-1024x1024.png\" class=\"attachment-large size-large wp-image-20131\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/07\/MINIMALISTIC-MAP-2026-1024x1024.png 1024w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/07\/MINIMALISTIC-MAP-2026-300x300.png 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/07\/MINIMALISTIC-MAP-2026-150x150.png 150w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/07\/MINIMALISTIC-MAP-2026-768x768.png 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/07\/MINIMALISTIC-MAP-2026-1536x1536.png 1536w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/07\/MINIMALISTIC-MAP-2026-2048x2048.png 2048w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/07\/MINIMALISTIC-MAP-2026-12x12.png 12w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f06bbc2 elementor-widget elementor-widget-text-editor\" data-id=\"f06bbc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6 style=\"text-align: center;\"><em>R\u00e9seau de sites et de formateurs<\/em><\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ea32355 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea32355\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-fb940d9\" data-id=\"fb940d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9dd8fae elementor-widget elementor-widget-custom-title-addons\" data-id=\"9dd8fae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"custom-title-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tpc-double_heading\"><div class=\"dbl__subtitle\"><span>La plupart de nos formations sont accr\u00e9dit\u00e9s par l'UE<\/span><\/div><h3 class=\"dbl__title-wrapper\"><span class=\"dbl__title dbl-title_1\">Apprenez <\/span><span class=\"dbl__title dbl-title_2\" style=\"position:relative;\" >et devenez un expert en migration avec l'Institut de formation MCP Med<span class=\"shape-bg\"><span class=\"shape__bg\"><\/span><\/span><\/span><\/h3><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f6a81b9\" data-id=\"f6a81b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6da89af elementor-align-center elementor-tablet-align-left elementor-mobile-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"6da89af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/drive.google.com\/drive\/folders\/1uPpBaa-LDQtU6M9K3m4vc5GgPpQdXV-b?usp=drive_link\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-link\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M326.612 185.391c59.747 59.809 58.927 155.698.36 214.59-.11.12-.24.25-.36.37l-67.2 67.2c-59.27 59.27-155.699 59.262-214.96 0-59.27-59.26-59.27-155.7 0-214.96l37.106-37.106c9.84-9.84 26.786-3.3 27.294 10.606.648 17.722 3.826 35.527 9.69 52.721 1.986 5.822.567 12.262-3.783 16.612l-13.087 13.087c-28.026 28.026-28.905 73.66-1.155 101.96 28.024 28.579 74.086 28.749 102.325.51l67.2-67.19c28.191-28.191 28.073-73.757 0-101.83-3.701-3.694-7.429-6.564-10.341-8.569a16.037 16.037 0 0 1-6.947-12.606c-.396-10.567 3.348-21.456 11.698-29.806l21.054-21.055c5.521-5.521 14.182-6.199 20.584-1.731a152.482 152.482 0 0 1 20.522 17.197zM467.547 44.449c-59.261-59.262-155.69-59.27-214.96 0l-67.2 67.2c-.12.12-.25.25-.36.37-58.566 58.892-59.387 154.781.36 214.59a152.454 152.454 0 0 0 20.521 17.196c6.402 4.468 15.064 3.789 20.584-1.731l21.054-21.055c8.35-8.35 12.094-19.239 11.698-29.806a16.037 16.037 0 0 0-6.947-12.606c-2.912-2.005-6.64-4.875-10.341-8.569-28.073-28.073-28.191-73.639 0-101.83l67.2-67.19c28.239-28.239 74.3-28.069 102.325.51 27.75 28.3 26.872 73.934-1.155 101.96l-13.087 13.087c-4.35 4.35-5.769 10.79-3.783 16.612 5.864 17.194 9.042 34.999 9.69 52.721.509 13.906 17.454 20.446 27.294 10.606l37.106-37.106c59.271-59.259 59.271-155.699.001-214.959z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Catalogue des cours<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e477a5d\" data-id=\"e477a5d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70db03e elementor-align-center elementor-tablet-align-left elementor-mobile-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"70db03e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-link\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M326.612 185.391c59.747 59.809 58.927 155.698.36 214.59-.11.12-.24.25-.36.37l-67.2 67.2c-59.27 59.27-155.699 59.262-214.96 0-59.27-59.26-59.27-155.7 0-214.96l37.106-37.106c9.84-9.84 26.786-3.3 27.294 10.606.648 17.722 3.826 35.527 9.69 52.721 1.986 5.822.567 12.262-3.783 16.612l-13.087 13.087c-28.026 28.026-28.905 73.66-1.155 101.96 28.024 28.579 74.086 28.749 102.325.51l67.2-67.19c28.191-28.191 28.073-73.757 0-101.83-3.701-3.694-7.429-6.564-10.341-8.569a16.037 16.037 0 0 1-6.947-12.606c-.396-10.567 3.348-21.456 11.698-29.806l21.054-21.055c5.521-5.521 14.182-6.199 20.584-1.731a152.482 152.482 0 0 1 20.522 17.197zM467.547 44.449c-59.261-59.262-155.69-59.27-214.96 0l-67.2 67.2c-.12.12-.25.25-.36.37-58.566 58.892-59.387 154.781.36 214.59a152.454 152.454 0 0 0 20.521 17.196c6.402 4.468 15.064 3.789 20.584-1.731l21.054-21.055c8.35-8.35 12.094-19.239 11.698-29.806a16.037 16.037 0 0 0-6.947-12.606c-2.912-2.005-6.64-4.875-10.341-8.569-28.073-28.073-28.191-73.639 0-101.83l67.2-67.19c28.239-28.239 74.3-28.069 102.325.51 27.75 28.3 26.872 73.934-1.155 101.96l-13.087 13.087c-4.35 4.35-5.769 10.79-3.783 16.612 5.864 17.194 9.042 34.999 9.69 52.721.509 13.906 17.454 20.446 27.294 10.606l37.106-37.106c59.271-59.259 59.271-155.699.001-214.959z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche d'information<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cdbc523 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cdbc523\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-23193c4 elementor-invisible\" data-id=\"23193c4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInLeft&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1106c1a elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1106c1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2023\/07\/Letter-to-CDEDU-members-Etined-recommendation-on-countering-Education-Fraud.pdf\" target=\"_blank\" rel=\"nofollow\" tabindex=\"-1\"><img decoding=\"async\" width=\"640\" height=\"630\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/07\/quality-768x756.png\" class=\"elementor-animation-grow attachment-medium_large size-medium_large wp-image-17114\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/07\/quality-768x756.png 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/07\/quality-300x295.png 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/07\/quality-1024x1008.png 1024w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/07\/quality.png 1200w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/a><\/figure><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9854c9f elementor-view-default elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-edubin-custom-icon\" data-id=\"9854c9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-custom-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-icon-box-wrapper\">\n                        <div class=\"elementor-icon-box-icon\">\n                <span class=\"elementor-icon elementor-animation-\" >\n\n                \n                        \n                            <i><img decoding=\"async\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/07\/quality.png\" title=\"qualit\u00e9\" alt=\"quality\" loading=\"lazy\" \/><\/i>\n\n                    \n                <\/span>\n            <\/div>\n                        <div class=\"elementor-icon-box-content\">\n                <h3 class=\"elementor-icon-box-title\">\n                    <span  >\n                        Qualit\u00e9                    <\/span>\n                <\/h3>\n                            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b0f4b9 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"1b0f4b9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/1759747804463.jpg\" class=\"attachment-full size-full wp-image-19194\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/1759747804463.jpg 2048w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/1759747804463-300x200.jpg 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/1759747804463-1024x683.jpg 1024w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/1759747804463-768x512.jpg 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/1759747804463-1536x1024.jpg 1536w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/1759747804463-18x12.jpg 18w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Une formation efficace con\u00e7ue pour transf\u00e9rer les m\u00e9thodes, les outils et les approches permettant de r\u00e9pondre de mani\u00e8re efficace et proactive aux nouvelles priorit\u00e9s en mati\u00e8re de migration, tant au niveau national que r\u00e9gional.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0941a3d elementor-invisible\" data-id=\"0941a3d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInLeft&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b9e3653 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"b9e3653\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/07\/partnership.png\" title=\"partenariat\" alt=\"partnership\" loading=\"lazy\" \/><\/figure><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c49ddb2 elementor-view-default elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-edubin-custom-icon\" data-id=\"c49ddb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-custom-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-icon-box-wrapper\">\n                        <div class=\"elementor-icon-box-icon\">\n                <span class=\"elementor-icon elementor-animation-\" >\n\n                \n                        \n                            <i><img decoding=\"async\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/07\/partnership.png\" title=\"partenariat\" alt=\"partnership\" loading=\"lazy\" \/><\/i>\n\n                    \n                <\/span>\n            <\/div>\n                        <div class=\"elementor-icon-box-content\">\n                <h3 class=\"elementor-icon-box-title\">\n                    <span  >\n                        Partenariat                    <\/span>\n                <\/h3>\n                            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43cbfc1 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"43cbfc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1134\" height=\"756\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/CHL09663-1.jpg\" class=\"attachment-full size-full wp-image-19200\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/CHL09663-1.jpg 1134w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/CHL09663-1-300x200.jpg 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/CHL09663-1-1024x683.jpg 1024w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/CHL09663-1-768x512.jpg 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/CHL09663-1-18x12.jpg 18w\" sizes=\"(max-width: 1134px) 100vw, 1134px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Promouvoir et favoriser un environnement organisationnel qui valorise le d\u00e9veloppement, le dialogue, les initiatives conjointes et la coop\u00e9ration multilat\u00e9rale.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a2e0674 elementor-invisible\" data-id=\"a2e0674\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInLeft&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfb6619 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"cfb6619\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/07\/accessibility.png\" title=\"l&#039;accessibilit\u00e9\" alt=\"accessibility\" loading=\"lazy\" \/><\/figure><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d725536 elementor-view-default elementor-position-top elementor-vertical-align-top elementor-widget elementor-widget-edubin-custom-icon\" data-id=\"d725536\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-custom-icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"elementor-icon-box-wrapper\">\n                        <div class=\"elementor-icon-box-icon\">\n                <span class=\"elementor-icon elementor-animation-\" >\n\n                \n                        \n                            <i><img decoding=\"async\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/07\/accessibility.png\" title=\"l&#039;accessibilit\u00e9\" alt=\"accessibility\" loading=\"lazy\" \/><\/i>\n\n                    \n                <\/span>\n            <\/div>\n                        <div class=\"elementor-icon-box-content\">\n                <h3 class=\"elementor-icon-box-title\">\n                    <span  >\n                        Accessibilit\u00e9                    <\/span>\n                <\/h3>\n                            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43e4c2c elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"43e4c2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1134\" height=\"756\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/CHL09747-1-1.jpg\" class=\"attachment-full size-full wp-image-19202\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/CHL09747-1-1.jpg 1134w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/CHL09747-1-1-300x200.jpg 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/CHL09747-1-1-1024x683.jpg 1024w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/CHL09747-1-1-768x512.jpg 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/CHL09747-1-1-18x12.jpg 18w\" sizes=\"(max-width: 1134px) 100vw, 1134px\" \/><\/figure><div class=\"elementor-image-box-content\"><p class=\"elementor-image-box-description\">Exploitation de la technologie, des ressources et des outils pour am\u00e9liorer et renforcer l'efficacit\u00e9 du flux de travail.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-355a3522 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"355a3522\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b8cda86\" data-id=\"5b8cda86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6b11f808 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"6b11f808\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1979e505\" data-id=\"1979e505\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30d2ad40 elementor-widget elementor-widget-counter\" data-id=\"30d2ad40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Formateurs<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1500\" data-to-value=\"158\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5729d42 elementor-widget elementor-widget-text-editor\" data-id=\"5729d42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">dont 84 % proviennent de la r\u00e9gion MENA et 16 % des \u00c9tats membres de l'UE.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-443e60bb elementor-absolute elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"443e60bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-3ddb3101\" data-id=\"3ddb3101\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56d67de elementor-widget elementor-widget-counter\" data-id=\"56d67de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">\u00c9tudiants (Participants)<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1500\" data-to-value=\"2423\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a82b1f4 elementor-absolute elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7a82b1f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d299a43 elementor-widget elementor-widget-text-editor\" data-id=\"d299a43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">dont 1150 certifi\u00e9s UE.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-18a0bb5f\" data-id=\"18a0bb5f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-842f97b elementor-widget elementor-widget-counter\" data-id=\"842f97b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Localisation des sites<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1500\" data-to-value=\"20\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66dbd94c elementor-absolute elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"66dbd94c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75548dc elementor-widget elementor-widget-text-editor\" data-id=\"75548dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">dans 9 pays.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-204d15ca\" data-id=\"204d15ca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-460a03ff elementor-widget elementor-widget-counter\" data-id=\"460a03ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Cours<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"1500\" data-to-value=\"92\" data-from-value=\"0\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\"><\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5773c59a elementor-absolute elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"5773c59a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c9e443 elementor-widget elementor-widget-text-editor\" data-id=\"8c9e443\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">con\u00e7us dont 41 sont accr\u00e9dit\u00e9s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12f02180 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12f02180\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-178a7572\" data-id=\"178a7572\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-265d155a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"265d155a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-40a9bc21 elementor-invisible\" data-id=\"40a9bc21\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a7adcf edubin-title-align-center elementor-invisible elementor-widget elementor-widget-section-title-addons\" data-id=\"8a7adcf\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"section-title-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"edubin-section-title edubin-subtitle-position-top title-style-four\">\r\n                <h2 class=\"section-title-txt\">T\u00e9moignages\n<\/h2><div class=\"edubin-title-sperator-sec\"><span class=\"edubin-title-sperator\">&nbsp;<\/span><\/div><p class=\"section-subtitle-txt\">De la part de nos participants<\/p>            <\/div>\r\n\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e7b214b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7b214b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f0c6931 elementor-invisible\" data-id=\"f0c6931\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bdfa097 elementor-widget elementor-widget-video\" data-id=\"bdfa097\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2024\/08\/Interview-Sarah-Saleh.mp4\" controls=\"\" preload=\"metadata\" controlslist=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1f803b elementor-widget elementor-widget-text-editor\" data-id=\"c1f803b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6 style=\"text-align: center;\"><em>T\u00e9moignage de formateur<\/em><\/h6>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-5139413 elementor-invisible\" data-id=\"5139413\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1659358 elementor-widget elementor-widget-edubin-testimonial-addons\" data-id=\"1659358\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-testimonial-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"tpc-testimonial_wrapper edubin-testi-style edubin-pagination edubin-navigation\" data-settings=\"{&quot;infinite_loop&quot;:false,&quot;autoplay&quot;:false,&quot;autoplay_speed&quot;:0,&quot;display_columns&quot;:1,&quot;item_gap&quot;:20,&quot;center_slides&quot;:false,&quot;pause_on_hover&quot;:false,&quot;pause_on_interaction&quot;:false,&quot;display_columns_tablet&quot;:2,&quot;tablet_item_gap&quot;:20,&quot;center_slides_tablet&quot;:false,&quot;display_columns_mobile&quot;:1,&quot;mobile_item_gap&quot;:20,&quot;center_slides_mobile&quot;:false}\"><div class=\"tpc_testimonial edubin-testi-4  edubin-testimonial-style-4 swiper swiper-container\"><div class=\"swiper-wrapper\"><div class=\"swiper-slide\"><div class=\"tpc-testimonial-item elementor-repeater-item-2f178a1\"><div class=\"edubin-testi-single\"><div class=\"testi-icon-wrap\"><svg \nxmlns=\"http:\/\/www.w3.org\/2000\/svg\"\nxmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"\nwidth=\"61px\" height=\"40px\">\n<path fill-rule=\"evenodd\"  fill=\"#325CAA\"\nd=\"M41.139,39.999 L19.860,39.999 C8.892,39.999 -0.000,31.045 -0.000,19.998 C-0.000,8.952 8.892,-0.001 19.860,-0.001 L41.139,-0.001 C52.108,-0.001 61.000,8.952 61.000,19.998 C61.000,25.702 61.000,39.999 61.000,39.999 C61.000,39.999 46.445,39.999 41.139,39.999 Z\"\/>\n<path fill-rule=\"evenodd\"  fill=\"#FFFFFF\"\nd=\"M46.000,24.777 C46.000,28.760 42.819,32.000 38.908,32.000 C35.096,32.000 32.114,28.978 31.816,24.813 C31.308,17.720 34.819,11.932 37.980,9.129 C38.075,9.046 38.191,9.005 38.308,9.005 C38.429,9.005 38.549,9.049 38.644,9.136 C38.925,9.396 39.117,9.595 39.537,10.031 C39.858,10.364 40.317,10.840 41.059,11.596 C41.229,11.770 41.254,12.042 41.117,12.245 C39.303,14.927 39.255,16.856 39.319,17.563 C43.039,17.782 46.000,20.933 46.000,24.777 ZM40.062,12.020 C39.484,11.429 39.102,11.033 38.824,10.744 C38.595,10.507 38.440,10.346 38.304,10.210 C36.897,11.581 32.242,16.761 32.813,24.740 C33.072,28.357 35.635,30.982 38.908,30.982 C42.267,30.982 45.001,28.199 45.001,24.777 C45.001,21.354 42.267,18.570 38.908,18.570 C38.722,18.570 38.545,18.456 38.459,18.290 C38.277,17.937 37.861,15.476 40.062,12.020 ZM21.159,32.000 C17.349,32.000 14.366,28.978 14.067,24.814 L14.067,24.813 C13.560,17.721 17.071,11.932 20.232,9.130 C20.326,9.046 20.443,9.005 20.560,9.005 C20.680,9.005 20.801,9.049 20.896,9.136 C21.178,9.396 21.371,9.596 21.793,10.035 C22.114,10.367 22.572,10.843 23.311,11.596 C23.481,11.770 23.506,12.042 23.369,12.245 C21.555,14.928 21.506,16.856 21.570,17.563 C25.291,17.782 28.252,20.933 28.252,24.777 C28.252,28.760 25.070,32.000 21.159,32.000 ZM21.159,18.570 C20.974,18.570 20.796,18.456 20.710,18.290 C20.528,17.937 20.113,15.476 22.314,12.020 C21.738,11.432 21.358,11.037 21.080,10.749 C20.849,10.510 20.692,10.347 20.555,10.210 C19.149,11.581 14.493,16.762 15.064,24.740 C15.323,28.357 17.887,30.982 21.159,30.982 C24.519,30.982 27.253,28.199 27.253,24.777 C27.253,21.354 24.519,18.570 21.159,18.570 Z\"\/>\n<\/svg><\/div><div class=\"testi-content\"><p class=\"client-say\">Je suis reconnaissant aux organisateurs de ce cours et \u00e0 l'institut pour leur concentration sur le domaine de la migration et pour avoir \u00e9tabli un institut sp\u00e9cialis\u00e9 dans les domaines de la migration. Je tiens \u00e9galement \u00e0 remercier le personnel qui nous accompagne ici dans cet institut.\nJe me r\u00e9jouis de la possibilit\u00e9 de suivre d'autres cours \u00e0 l'avenir qui contribueront \u00e0 consolider et \u00e0 am\u00e9liorer les acquis de ce cours, et \u00e0 d\u00e9velopper davantage les comp\u00e9tences de ceux qui travaillent dans les institutions publiques des deux pays, la Tunisie et la Jordanie.<\/p><\/div><div class=\"testi-thum-degree-wrap\"><div class=\"testi-img\"><img decoding=\"async\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/><\/div><div class=\"testi-name-degree\"><h6 class=\"name\">Participant de Tunisie<\/h6><p class=\"degree\">Formation Professionnelle Train the Trainer<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"tpc-testimonial-item elementor-repeater-item-3af594c\"><div class=\"edubin-testi-single\"><div class=\"testi-icon-wrap\"><svg \nxmlns=\"http:\/\/www.w3.org\/2000\/svg\"\nxmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\"\nwidth=\"61px\" height=\"40px\">\n<path fill-rule=\"evenodd\"  fill=\"#325CAA\"\nd=\"M41.139,39.999 L19.860,39.999 C8.892,39.999 -0.000,31.045 -0.000,19.998 C-0.000,8.952 8.892,-0.001 19.860,-0.001 L41.139,-0.001 C52.108,-0.001 61.000,8.952 61.000,19.998 C61.000,25.702 61.000,39.999 61.000,39.999 C61.000,39.999 46.445,39.999 41.139,39.999 Z\"\/>\n<path fill-rule=\"evenodd\"  fill=\"#FFFFFF\"\nd=\"M46.000,24.777 C46.000,28.760 42.819,32.000 38.908,32.000 C35.096,32.000 32.114,28.978 31.816,24.813 C31.308,17.720 34.819,11.932 37.980,9.129 C38.075,9.046 38.191,9.005 38.308,9.005 C38.429,9.005 38.549,9.049 38.644,9.136 C38.925,9.396 39.117,9.595 39.537,10.031 C39.858,10.364 40.317,10.840 41.059,11.596 C41.229,11.770 41.254,12.042 41.117,12.245 C39.303,14.927 39.255,16.856 39.319,17.563 C43.039,17.782 46.000,20.933 46.000,24.777 ZM40.062,12.020 C39.484,11.429 39.102,11.033 38.824,10.744 C38.595,10.507 38.440,10.346 38.304,10.210 C36.897,11.581 32.242,16.761 32.813,24.740 C33.072,28.357 35.635,30.982 38.908,30.982 C42.267,30.982 45.001,28.199 45.001,24.777 C45.001,21.354 42.267,18.570 38.908,18.570 C38.722,18.570 38.545,18.456 38.459,18.290 C38.277,17.937 37.861,15.476 40.062,12.020 ZM21.159,32.000 C17.349,32.000 14.366,28.978 14.067,24.814 L14.067,24.813 C13.560,17.721 17.071,11.932 20.232,9.130 C20.326,9.046 20.443,9.005 20.560,9.005 C20.680,9.005 20.801,9.049 20.896,9.136 C21.178,9.396 21.371,9.596 21.793,10.035 C22.114,10.367 22.572,10.843 23.311,11.596 C23.481,11.770 23.506,12.042 23.369,12.245 C21.555,14.928 21.506,16.856 21.570,17.563 C25.291,17.782 28.252,20.933 28.252,24.777 C28.252,28.760 25.070,32.000 21.159,32.000 ZM21.159,18.570 C20.974,18.570 20.796,18.456 20.710,18.290 C20.528,17.937 20.113,15.476 22.314,12.020 C21.738,11.432 21.358,11.037 21.080,10.749 C20.849,10.510 20.692,10.347 20.555,10.210 C19.149,11.581 14.493,16.762 15.064,24.740 C15.323,28.357 17.887,30.982 21.159,30.982 C24.519,30.982 27.253,28.199 27.253,24.777 C27.253,21.354 24.519,18.570 21.159,18.570 Z\"\/>\n<\/svg><\/div><div class=\"testi-content\"><p class=\"client-say\">Je suis ravi de cette pr\u00e9cieuse opportunit\u00e9 d'am\u00e9liorer mes comp\u00e9tences professionnelles gr\u00e2ce \u00e0 cette formation sur les questions de migration. La rencontre avec des participants de divers pays, y compris la Jordanie, a \u00e9t\u00e9 enrichissante. Ce cours a apport\u00e9 d'immenses avantages professionnels, am\u00e9liorant mes connaissances et mes comp\u00e9tences en mati\u00e8re de migration. J'adresse mes sinc\u00e8res remerciements \u00e0 tous ceux qui ont rendu cela possible.<\/p><\/div><div class=\"testi-thum-degree-wrap\"><div class=\"testi-img\"><img decoding=\"async\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/plugins\/elementor\/assets\/images\/placeholder.png\" title=\"\" alt=\"\" loading=\"lazy\" \/><\/div><div class=\"testi-name-degree\"><h6 class=\"name\">Participant de Tunisie<\/h6><p class=\"degree\">Formation Professionnelle Train the Trainer<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"testi-pagination swiper-pagination\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4d3e897 elementor-invisible\" data-id=\"4d3e897\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-249b162 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"249b162\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3274660\" data-id=\"3274660\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2c03f47 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c03f47\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-50a6e89\" data-id=\"50a6e89\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86a4380 edubin-title-align-center elementor-invisible elementor-widget elementor-widget-section-title-addons\" data-id=\"86a4380\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"section-title-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"edubin-section-title edubin-subtitle-position-top title-style-four\">\r\n                <h2 class=\"section-title-txt\">MCP Med Training Institute Derni\u00e8res nouvelles et \u00e9v\u00e9nements<\/h2><div class=\"edubin-title-sperator-sec\"><span class=\"edubin-title-sperator\">&nbsp;<\/span><\/div><p class=\"section-subtitle-txt\">Actualit\u00e9s et \u00e9v\u00e9nements<\/p>            <\/div>\r\n\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db5c181 elementor-invisible elementor-widget elementor-widget-edubin-latest-post\" data-id=\"db5c181\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"edubin-latest-post.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"edubin-row tpc_g_30 edubin-latest-news layout-5\"><div class=\"edubin-col-12 edubin-col-sm-6 edubin-col-md-6 edubin-col-lg-4\" data-sal><div class=\"edu-blog blog-style-1\"><div class=\"inner\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"788\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/07\/\ud835\udc12\ud835\udc2d\ud835\udc2b\ud835\udc1e\ud835\udc27\ud835\udc20\ud835\udc2d\ud835\udc21\ud835\udc1e\ud835\udc27\ud835\udc22\ud835\udc27\ud835\udc20-\ud835\udc11\ud835\udc1e\ud835\udc20\ud835\udc22\ud835\udc28\ud835\udc27\ud835\udc1a\ud835\udc25-\ud835\udc00\ud835\udc1c\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27-\ud835\udc00\ud835\udc20\ud835\udc1a\ud835\udc22\ud835\udc27\ud835\udc2c\ud835\udc2d-\ud835\udc13\ud835\udc2b\ud835\udc1a\ud835\udc1f\ud835\udc1f\ud835\udc22\ud835\udc1c\ud835\udc24\ud835\udc22\ud835\udc27\ud835\udc20-\ud835\udc22\ud835\udc27-\ud835\udc07\ud835\udc2e\ud835\udc26\ud835\udc1a\ud835\udc27-\ud835\udc01\ud835\udc1e\ud835\udc22\ud835\udc27\ud835\udc20\ud835\udc2c.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/07\/\ud835\udc12\ud835\udc2d\ud835\udc2b\ud835\udc1e\ud835\udc27\ud835\udc20\ud835\udc2d\ud835\udc21\ud835\udc1e\ud835\udc27\ud835\udc22\ud835\udc27\ud835\udc20-\ud835\udc11\ud835\udc1e\ud835\udc20\ud835\udc22\ud835\udc28\ud835\udc27\ud835\udc1a\ud835\udc25-\ud835\udc00\ud835\udc1c\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27-\ud835\udc00\ud835\udc20\ud835\udc1a\ud835\udc22\ud835\udc27\ud835\udc2c\ud835\udc2d-\ud835\udc13\ud835\udc2b\ud835\udc1a\ud835\udc1f\ud835\udc1f\ud835\udc22\ud835\udc1c\ud835\udc24\ud835\udc22\ud835\udc27\ud835\udc20-\ud835\udc22\ud835\udc27-\ud835\udc07\ud835\udc2e\ud835\udc26\ud835\udc1a\ud835\udc27-\ud835\udc01\ud835\udc1e\ud835\udc22\ud835\udc27\ud835\udc20\ud835\udc2c.jpg 940w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/07\/\ud835\udc12\ud835\udc2d\ud835\udc2b\ud835\udc1e\ud835\udc27\ud835\udc20\ud835\udc2d\ud835\udc21\ud835\udc1e\ud835\udc27\ud835\udc22\ud835\udc27\ud835\udc20-\ud835\udc11\ud835\udc1e\ud835\udc20\ud835\udc22\ud835\udc28\ud835\udc27\ud835\udc1a\ud835\udc25-\ud835\udc00\ud835\udc1c\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27-\ud835\udc00\ud835\udc20\ud835\udc1a\ud835\udc22\ud835\udc27\ud835\udc2c\ud835\udc2d-\ud835\udc13\ud835\udc2b\ud835\udc1a\ud835\udc1f\ud835\udc1f\ud835\udc22\ud835\udc1c\ud835\udc24\ud835\udc22\ud835\udc27\ud835\udc20-\ud835\udc22\ud835\udc27-\ud835\udc07\ud835\udc2e\ud835\udc26\ud835\udc1a\ud835\udc27-\ud835\udc01\ud835\udc1e\ud835\udc22\ud835\udc27\ud835\udc20\ud835\udc2c-300x251.jpg 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/07\/\ud835\udc12\ud835\udc2d\ud835\udc2b\ud835\udc1e\ud835\udc27\ud835\udc20\ud835\udc2d\ud835\udc21\ud835\udc1e\ud835\udc27\ud835\udc22\ud835\udc27\ud835\udc20-\ud835\udc11\ud835\udc1e\ud835\udc20\ud835\udc22\ud835\udc28\ud835\udc27\ud835\udc1a\ud835\udc25-\ud835\udc00\ud835\udc1c\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27-\ud835\udc00\ud835\udc20\ud835\udc1a\ud835\udc22\ud835\udc27\ud835\udc2c\ud835\udc2d-\ud835\udc13\ud835\udc2b\ud835\udc1a\ud835\udc1f\ud835\udc1f\ud835\udc22\ud835\udc1c\ud835\udc24\ud835\udc22\ud835\udc27\ud835\udc20-\ud835\udc22\ud835\udc27-\ud835\udc07\ud835\udc2e\ud835\udc26\ud835\udc1a\ud835\udc27-\ud835\udc01\ud835\udc1e\ud835\udc22\ud835\udc27\ud835\udc20\ud835\udc2c-768x644.jpg 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/07\/\ud835\udc12\ud835\udc2d\ud835\udc2b\ud835\udc1e\ud835\udc27\ud835\udc20\ud835\udc2d\ud835\udc21\ud835\udc1e\ud835\udc27\ud835\udc22\ud835\udc27\ud835\udc20-\ud835\udc11\ud835\udc1e\ud835\udc20\ud835\udc22\ud835\udc28\ud835\udc27\ud835\udc1a\ud835\udc25-\ud835\udc00\ud835\udc1c\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27-\ud835\udc00\ud835\udc20\ud835\udc1a\ud835\udc22\ud835\udc27\ud835\udc2c\ud835\udc2d-\ud835\udc13\ud835\udc2b\ud835\udc1a\ud835\udc1f\ud835\udc1f\ud835\udc22\ud835\udc1c\ud835\udc24\ud835\udc22\ud835\udc27\ud835\udc20-\ud835\udc22\ud835\udc27-\ud835\udc07\ud835\udc2e\ud835\udc26\ud835\udc1a\ud835\udc27-\ud835\udc01\ud835\udc1e\ud835\udc22\ud835\udc27\ud835\udc20\ud835\udc2c-14x12.jpg 14w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><div class=\"content\"><ul class=\"blog-meta\"><li class=\"byline list-inline-item\"><span class=\"author vcard\"><img alt='' src='https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI.png' srcset='https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI.png 2x' class='avatar avatar-32 photo' height='32' width='32' \/><a class=\"url fn n\" href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/author\/admin\/\">MCP Med TI<\/a><\/li><\/span><li class=\"meta-blog-cat\"><i class=\"flaticon-folder\"><\/i><a href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/category\/events\/\">\u00c9v\u00e9nements<\/a><\/li><\/ul><a href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/strengthening-regional-action-against-trafficking-in-human-beings\/\"><h3 class=\"news-title\">Renforcement de l'action r\u00e9gionale contre la traite des \u00eatres humains<\/h3><\/a><p>\ud83d\ude80 Cet \u00e9t\u00e9, la toute premi\u00e8re \u00e9dition de l'Award in...<\/p>\n<\/div><\/div><\/div><\/div><div class=\"edubin-col-12 edubin-col-sm-6 edubin-col-md-6 edubin-col-lg-4\" data-sal><div class=\"edu-blog blog-style-1\"><div class=\"inner\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"788\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/12\/Kicking-Off-a-Week-of-hashtagRegional-Impact.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/12\/Kicking-Off-a-Week-of-hashtagRegional-Impact.jpg 940w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/12\/Kicking-Off-a-Week-of-hashtagRegional-Impact-300x251.jpg 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/12\/Kicking-Off-a-Week-of-hashtagRegional-Impact-768x644.jpg 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/12\/Kicking-Off-a-Week-of-hashtagRegional-Impact-14x12.jpg 14w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><div class=\"content\"><ul class=\"blog-meta\"><li class=\"byline list-inline-item\"><span class=\"author vcard\"><img alt='' src='https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI.png' srcset='https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI.png 2x' class='avatar avatar-32 photo' height='32' width='32' \/><a class=\"url fn n\" href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/author\/admin\/\">MCP Med TI<\/a><\/li><\/span><li class=\"meta-blog-cat\"><i class=\"flaticon-folder\"><\/i><a href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/category\/events\/\">\u00c9v\u00e9nements<\/a><\/li><\/ul><a href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/kicking-off-a-week-of-hashtagregional-impact-%f0%9f%8c%8d\/\"><h3 class=\"news-title\">Coup d'envoi d'une semaine d'impact r\u00e9gional \ud83c\udf0d<\/h3><\/a><p>Aujourd'hui \u00e0 La Valette, l'Institut de formation sur la capacit\u00e9 migratoire Partenariat pour...<\/p>\n<\/div><\/div><\/div><\/div><div class=\"edubin-col-12 edubin-col-sm-6 edubin-col-md-6 edubin-col-lg-4\" data-sal><div class=\"edu-blog blog-style-1\"><div class=\"inner\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/01\/A-Week-of-Regional-Cooperation-in-Action.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/01\/A-Week-of-Regional-Cooperation-in-Action.jpg 2048w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/01\/A-Week-of-Regional-Cooperation-in-Action-300x200.jpg 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/01\/A-Week-of-Regional-Cooperation-in-Action-1024x683.jpg 1024w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/01\/A-Week-of-Regional-Cooperation-in-Action-768x512.jpg 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/01\/A-Week-of-Regional-Cooperation-in-Action-1536x1024.jpg 1536w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2026\/01\/A-Week-of-Regional-Cooperation-in-Action-18x12.jpg 18w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><div class=\"content\"><ul class=\"blog-meta\"><li class=\"byline list-inline-item\"><span class=\"author vcard\"><img alt='' src='https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI.png' srcset='https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI.png 2x' class='avatar avatar-32 photo' height='32' width='32' \/><a class=\"url fn n\" href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/author\/admin\/\">MCP Med TI<\/a><\/li><\/span><li class=\"meta-blog-cat\"><i class=\"flaticon-folder\"><\/i><a href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/category\/events\/\">\u00c9v\u00e9nements<\/a><\/li><\/ul><a href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/its-a-wrap-a-week-of-regional-cooperation-in-action-%f0%9f%8c%8d%e2%9c%a8\/\"><h3 class=\"news-title\">C'est termin\u00e9 : Une semaine de coop\u00e9ration r\u00e9gionale en action \ud83c\udf0d\u2728\u2728<\/h3><\/a><p>La semaine derni\u00e8re \u00e0 La Valette, des professionnels de Jordanie \ud83c\uddef\ud83c\uddf4, du Liban \ud83c\uddf1\ud83c\udde7, et...<\/p>\n<\/div><\/div><\/div><\/div><div class=\"edubin-col-12 edubin-col-sm-6 edubin-col-md-6 edubin-col-lg-4\" data-sal><div class=\"edu-blog blog-style-1\"><div class=\"inner\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/11\/\ud835\udde7\ud835\uddf5\ud835\uddf2-\ud835\udde7\ud835\uddff\ud835\uddee\ud835\uddf6\ud835\uddfb\ud835\uddf6\ud835\uddfb\ud835\uddf4-\ud835\udddc\ud835\uddfb\ud835\ude00\ud835\ude01\ud835\uddf6\ud835\ude01\ud835\ude02\ud835\ude01\ud835\uddf2-\ud835\uddee\ud835\uddfb\ud835\uddf1-\ud835\ude01\ud835\uddf5\ud835\uddf2-\ud835\udde3\ud835\uddee\ud835\uddf0\ud835\ude01-\ud835\uddf3\ud835\uddfc\ud835\uddff-\ud835\ude01\ud835\uddf5\ud835\uddf2-\ud835\udde0\ud835\uddf2\ud835\uddf1\ud835\uddf6\ud835\ude01\ud835\uddf2\ud835\uddff\ud835\uddff\ud835\uddee\ud835\uddfb\ud835\uddf2\ud835\uddee\ud835\uddfb.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/11\/\ud835\udde7\ud835\uddf5\ud835\uddf2-\ud835\udde7\ud835\uddff\ud835\uddee\ud835\uddf6\ud835\uddfb\ud835\uddf6\ud835\uddfb\ud835\uddf4-\ud835\udddc\ud835\uddfb\ud835\ude00\ud835\ude01\ud835\uddf6\ud835\ude01\ud835\ude02\ud835\ude01\ud835\uddf2-\ud835\uddee\ud835\uddfb\ud835\uddf1-\ud835\ude01\ud835\uddf5\ud835\uddf2-\ud835\udde3\ud835\uddee\ud835\uddf0\ud835\ude01-\ud835\uddf3\ud835\uddfc\ud835\uddff-\ud835\ude01\ud835\uddf5\ud835\uddf2-\ud835\udde0\ud835\uddf2\ud835\uddf1\ud835\uddf6\ud835\ude01\ud835\uddf2\ud835\uddff\ud835\uddff\ud835\uddee\ud835\uddfb\ud835\uddf2\ud835\uddee\ud835\uddfb.jpg 2048w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/11\/\ud835\udde7\ud835\uddf5\ud835\uddf2-\ud835\udde7\ud835\uddff\ud835\uddee\ud835\uddf6\ud835\uddfb\ud835\uddf6\ud835\uddfb\ud835\uddf4-\ud835\udddc\ud835\uddfb\ud835\ude00\ud835\ude01\ud835\uddf6\ud835\ude01\ud835\ude02\ud835\ude01\ud835\uddf2-\ud835\uddee\ud835\uddfb\ud835\uddf1-\ud835\ude01\ud835\uddf5\ud835\uddf2-\ud835\udde3\ud835\uddee\ud835\uddf0\ud835\ude01-\ud835\uddf3\ud835\uddfc\ud835\uddff-\ud835\ude01\ud835\uddf5\ud835\uddf2-\ud835\udde0\ud835\uddf2\ud835\uddf1\ud835\uddf6\ud835\ude01\ud835\uddf2\ud835\uddff\ud835\uddff\ud835\uddee\ud835\uddfb\ud835\uddf2\ud835\uddee\ud835\uddfb-300x200.jpg 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/11\/\ud835\udde7\ud835\uddf5\ud835\uddf2-\ud835\udde7\ud835\uddff\ud835\uddee\ud835\uddf6\ud835\uddfb\ud835\uddf6\ud835\uddfb\ud835\uddf4-\ud835\udddc\ud835\uddfb\ud835\ude00\ud835\ude01\ud835\uddf6\ud835\ude01\ud835\ude02\ud835\ude01\ud835\uddf2-\ud835\uddee\ud835\uddfb\ud835\uddf1-\ud835\ude01\ud835\uddf5\ud835\uddf2-\ud835\udde3\ud835\uddee\ud835\uddf0\ud835\ude01-\ud835\uddf3\ud835\uddfc\ud835\uddff-\ud835\ude01\ud835\uddf5\ud835\uddf2-\ud835\udde0\ud835\uddf2\ud835\uddf1\ud835\uddf6\ud835\ude01\ud835\uddf2\ud835\uddff\ud835\uddff\ud835\uddee\ud835\uddfb\ud835\uddf2\ud835\uddee\ud835\uddfb-1024x683.jpg 1024w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/11\/\ud835\udde7\ud835\uddf5\ud835\uddf2-\ud835\udde7\ud835\uddff\ud835\uddee\ud835\uddf6\ud835\uddfb\ud835\uddf6\ud835\uddfb\ud835\uddf4-\ud835\udddc\ud835\uddfb\ud835\ude00\ud835\ude01\ud835\uddf6\ud835\ude01\ud835\ude02\ud835\ude01\ud835\uddf2-\ud835\uddee\ud835\uddfb\ud835\uddf1-\ud835\ude01\ud835\uddf5\ud835\uddf2-\ud835\udde3\ud835\uddee\ud835\uddf0\ud835\ude01-\ud835\uddf3\ud835\uddfc\ud835\uddff-\ud835\ude01\ud835\uddf5\ud835\uddf2-\ud835\udde0\ud835\uddf2\ud835\uddf1\ud835\uddf6\ud835\ude01\ud835\uddf2\ud835\uddff\ud835\uddff\ud835\uddee\ud835\uddfb\ud835\uddf2\ud835\uddee\ud835\uddfb-768x512.jpg 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/11\/\ud835\udde7\ud835\uddf5\ud835\uddf2-\ud835\udde7\ud835\uddff\ud835\uddee\ud835\uddf6\ud835\uddfb\ud835\uddf6\ud835\uddfb\ud835\uddf4-\ud835\udddc\ud835\uddfb\ud835\ude00\ud835\ude01\ud835\uddf6\ud835\ude01\ud835\ude02\ud835\ude01\ud835\uddf2-\ud835\uddee\ud835\uddfb\ud835\uddf1-\ud835\ude01\ud835\uddf5\ud835\uddf2-\ud835\udde3\ud835\uddee\ud835\uddf0\ud835\ude01-\ud835\uddf3\ud835\uddfc\ud835\uddff-\ud835\ude01\ud835\uddf5\ud835\uddf2-\ud835\udde0\ud835\uddf2\ud835\uddf1\ud835\uddf6\ud835\ude01\ud835\uddf2\ud835\uddff\ud835\uddff\ud835\uddee\ud835\uddfb\ud835\uddf2\ud835\uddee\ud835\uddfb-1536x1024.jpg 1536w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/11\/\ud835\udde7\ud835\uddf5\ud835\uddf2-\ud835\udde7\ud835\uddff\ud835\uddee\ud835\uddf6\ud835\uddfb\ud835\uddf6\ud835\uddfb\ud835\uddf4-\ud835\udddc\ud835\uddfb\ud835\ude00\ud835\ude01\ud835\uddf6\ud835\ude01\ud835\ude02\ud835\ude01\ud835\uddf2-\ud835\uddee\ud835\uddfb\ud835\uddf1-\ud835\ude01\ud835\uddf5\ud835\uddf2-\ud835\udde3\ud835\uddee\ud835\uddf0\ud835\ude01-\ud835\uddf3\ud835\uddfc\ud835\uddff-\ud835\ude01\ud835\uddf5\ud835\uddf2-\ud835\udde0\ud835\uddf2\ud835\uddf1\ud835\uddf6\ud835\ude01\ud835\uddf2\ud835\uddff\ud835\uddff\ud835\uddee\ud835\uddfb\ud835\uddf2\ud835\uddee\ud835\uddfb-18x12.jpg 18w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/><div class=\"content\"><ul class=\"blog-meta\"><li class=\"byline list-inline-item\"><span class=\"author vcard\"><img alt='' src='https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI.png' srcset='https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI.png 2x' class='avatar avatar-32 photo' height='32' width='32' \/><a class=\"url fn n\" href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/author\/admin\/\">MCP Med TI<\/a><\/li><\/span><li class=\"meta-blog-cat\"><i class=\"flaticon-folder\"><\/i><a href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/category\/events\/\">\u00c9v\u00e9nements<\/a><\/li><\/ul><a href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/the-training-institute-and-the-pact-for-the-mediterranean\/\"><h3 class=\"news-title\">L'Institut de formation et le Pacte pour la M\u00e9diterran\u00e9e<\/h3><\/a><p>L'Institut de formation sur le Partenariat pour la capacit\u00e9 migratoire en M\u00e9diterran\u00e9e (PCM)...<\/p>\n<\/div><\/div><\/div><\/div><div class=\"edubin-col-12 edubin-col-sm-6 edubin-col-md-6 edubin-col-lg-4\" data-sal><div class=\"edu-blog blog-style-1\"><div class=\"inner\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"788\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/Induction-Course-for-Vocational-Training-of-Trainers-VTT.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/Induction-Course-for-Vocational-Training-of-Trainers-VTT.jpg 940w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/Induction-Course-for-Vocational-Training-of-Trainers-VTT-300x251.jpg 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/Induction-Course-for-Vocational-Training-of-Trainers-VTT-768x644.jpg 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/Induction-Course-for-Vocational-Training-of-Trainers-VTT-14x12.jpg 14w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><div class=\"content\"><ul class=\"blog-meta\"><li class=\"byline list-inline-item\"><span class=\"author vcard\"><img alt='' src='https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI.png' srcset='https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI.png 2x' class='avatar avatar-32 photo' height='32' width='32' \/><a class=\"url fn n\" href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/author\/admin\/\">MCP Med TI<\/a><\/li><\/span><li class=\"meta-blog-cat\"><i class=\"flaticon-folder\"><\/i><a href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/category\/events\/\">\u00c9v\u00e9nements<\/a><\/li><\/ul><a href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/induction-course-for-vocational-training-of-trainers-vtt\/\"><h3 class=\"news-title\">Cours d'initiation \u00e0 la formation professionnelle des formateurs (VTT)<\/h3><\/a><p>Du 22 au 26 septembre 2025, l'Institut de formation sur les migrations...<\/p>\n<\/div><\/div><\/div><\/div><div class=\"edubin-col-12 edubin-col-sm-6 edubin-col-md-6 edubin-col-lg-4\" data-sal><div class=\"edu-blog blog-style-1\"><div class=\"inner\"><img loading=\"lazy\" decoding=\"async\" width=\"940\" height=\"788\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/\ud835\udc0b\ud835\udc1a\ud835\udc2e\ud835\udc27\ud835\udc1c\ud835\udc21\ud835\udc22\ud835\udc27\ud835\udc20-\ud835\udc2d\ud835\udc21\ud835\udc1e-\ud835\udc05\ud835\udc22\ud835\udc2b\ud835\udc2c\ud835\udc2d-\ud835\udc04\ud835\udc1d\ud835\udc22\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27-\ud835\udc28\ud835\udc1f-\ud835\udc0b\ud835\udc1e\ud835\udc20\ud835\udc1a\ud835\udc25-\ud835\udc0c\ud835\udc22\ud835\udc20\ud835\udc2b\ud835\udc1a\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27-\ud835\udc04\ud835\udc2c\ud835\udc2c\ud835\udc1e\ud835\udc27\ud835\udc2d\ud835\udc22\ud835\udc1a\ud835\udc25\ud835\udc2c.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/\ud835\udc0b\ud835\udc1a\ud835\udc2e\ud835\udc27\ud835\udc1c\ud835\udc21\ud835\udc22\ud835\udc27\ud835\udc20-\ud835\udc2d\ud835\udc21\ud835\udc1e-\ud835\udc05\ud835\udc22\ud835\udc2b\ud835\udc2c\ud835\udc2d-\ud835\udc04\ud835\udc1d\ud835\udc22\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27-\ud835\udc28\ud835\udc1f-\ud835\udc0b\ud835\udc1e\ud835\udc20\ud835\udc1a\ud835\udc25-\ud835\udc0c\ud835\udc22\ud835\udc20\ud835\udc2b\ud835\udc1a\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27-\ud835\udc04\ud835\udc2c\ud835\udc2c\ud835\udc1e\ud835\udc27\ud835\udc2d\ud835\udc22\ud835\udc1a\ud835\udc25\ud835\udc2c.jpg 940w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/\ud835\udc0b\ud835\udc1a\ud835\udc2e\ud835\udc27\ud835\udc1c\ud835\udc21\ud835\udc22\ud835\udc27\ud835\udc20-\ud835\udc2d\ud835\udc21\ud835\udc1e-\ud835\udc05\ud835\udc22\ud835\udc2b\ud835\udc2c\ud835\udc2d-\ud835\udc04\ud835\udc1d\ud835\udc22\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27-\ud835\udc28\ud835\udc1f-\ud835\udc0b\ud835\udc1e\ud835\udc20\ud835\udc1a\ud835\udc25-\ud835\udc0c\ud835\udc22\ud835\udc20\ud835\udc2b\ud835\udc1a\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27-\ud835\udc04\ud835\udc2c\ud835\udc2c\ud835\udc1e\ud835\udc27\ud835\udc2d\ud835\udc22\ud835\udc1a\ud835\udc25\ud835\udc2c-300x251.jpg 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/\ud835\udc0b\ud835\udc1a\ud835\udc2e\ud835\udc27\ud835\udc1c\ud835\udc21\ud835\udc22\ud835\udc27\ud835\udc20-\ud835\udc2d\ud835\udc21\ud835\udc1e-\ud835\udc05\ud835\udc22\ud835\udc2b\ud835\udc2c\ud835\udc2d-\ud835\udc04\ud835\udc1d\ud835\udc22\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27-\ud835\udc28\ud835\udc1f-\ud835\udc0b\ud835\udc1e\ud835\udc20\ud835\udc1a\ud835\udc25-\ud835\udc0c\ud835\udc22\ud835\udc20\ud835\udc2b\ud835\udc1a\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27-\ud835\udc04\ud835\udc2c\ud835\udc2c\ud835\udc1e\ud835\udc27\ud835\udc2d\ud835\udc22\ud835\udc1a\ud835\udc25\ud835\udc2c-768x644.jpg 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2025\/10\/\ud835\udc0b\ud835\udc1a\ud835\udc2e\ud835\udc27\ud835\udc1c\ud835\udc21\ud835\udc22\ud835\udc27\ud835\udc20-\ud835\udc2d\ud835\udc21\ud835\udc1e-\ud835\udc05\ud835\udc22\ud835\udc2b\ud835\udc2c\ud835\udc2d-\ud835\udc04\ud835\udc1d\ud835\udc22\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27-\ud835\udc28\ud835\udc1f-\ud835\udc0b\ud835\udc1e\ud835\udc20\ud835\udc1a\ud835\udc25-\ud835\udc0c\ud835\udc22\ud835\udc20\ud835\udc2b\ud835\udc1a\ud835\udc2d\ud835\udc22\ud835\udc28\ud835\udc27-\ud835\udc04\ud835\udc2c\ud835\udc2c\ud835\udc1e\ud835\udc27\ud835\udc2d\ud835\udc22\ud835\udc1a\ud835\udc25\ud835\udc2c-14x12.jpg 14w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><div class=\"content\"><ul class=\"blog-meta\"><li class=\"byline list-inline-item\"><span class=\"author vcard\"><img alt='' src='https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI.png' srcset='https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI.png 2x' class='avatar avatar-32 photo' height='32' width='32' \/><a class=\"url fn n\" href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/author\/admin\/\">MCP Med TI<\/a><\/li><\/span><li class=\"meta-blog-cat\"><i class=\"flaticon-folder\"><\/i><a href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/category\/events\/\">\u00c9v\u00e9nements<\/a><\/li><\/ul><a href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/launching-the-first-edition-of-legal-migration-essentials-%f0%9f%9a%80\/\"><h3 class=\"news-title\">Lancement de la premi\u00e8re \u00e9dition de Legal Migration Essentials \ud83d\ude80 (L'essentiel sur la migration l\u00e9gale)<\/h3><\/a><p>La semaine derni\u00e8re, l'Institut de formation MCP Med a fi\u00e8rement pr\u00e9sent\u00e9 le...<\/p>\n<\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c79b69d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c79b69d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/news-events\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Afficher tout<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31a7505 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31a7505\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-81245f4\" data-id=\"81245f4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2e8b793 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e8b793\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ef17a48 elementor-invisible\" data-id=\"ef17a48\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;slideInLeft&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8509208 edubin-title-align-left elementor-invisible elementor-widget elementor-widget-section-title-addons\" data-id=\"8509208\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;}\" data-widget_type=\"section-title-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"edubin-section-title edubin-subtitle-position-top title-style-four\">\r\n                <h2 class=\"section-title-txt\">Rencontrez nos formateurs agr\u00e9\u00e9s<\/h2><div class=\"edubin-title-sperator-sec\"><span class=\"edubin-title-sperator\">&nbsp;<\/span><\/div><p class=\"section-subtitle-txt\">Les formateurs agr\u00e9\u00e9s<\/p>            <\/div>\r\n\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-481b544 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"481b544\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;,&quot;_animation_delay&quot;:100}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Embarquez pour votre voyage \u00e9ducatif en toute confiance en rencontrant nos formateurs qualifi\u00e9s pr\u00eats \u00e0 vous guider et \u00e0 vous inspirer.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3669d5f elementor-align-left elementor-tablet-align-left elementor-mobile-align-left elementor-invisible elementor-widget elementor-widget-button\" data-id=\"3669d5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;,&quot;_animation_delay&quot;:150}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/trainers\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Nos formateurs agr\u00e9\u00e9s<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c466877 elementor-invisible\" data-id=\"c466877\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:150}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc70681 elementor-widget elementor-widget-edubin-teacher-addons\" data-id=\"fc70681\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"edubin-teacher-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"edubin-row\" >\n\n                            <div class=\"edubin-col-xs-12 edubin-col-sm-6 edubin-col-md-6 edubin-col-lg-6\" >\n\n                    <div class=\"edubin-single-teacher text-center active-social\"><div class=\"teacher-image-wrap\"><a href=\"\" ><div class=\"teacher-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder.png\" class=\"attachment-full size-full wp-image-1065\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder.png 1200w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-300x300.png 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-100x100.png 100w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-600x600.png 600w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-1024x1024.png 1024w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-150x150.png 150w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-768x768.png 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-12x12.png 12w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div><\/a><\/div><div class=\"teacher-content-area\"><div class=\"teacher-content\"><a href=\"\" ><h6 class=\"teacher-name\">Sarah Saleh<\/h6><\/a><span class=\"teacher-degree\">Formateur Agr\u00e9\u00e9<\/span><div class=\"teacher-social\"><a href=\"https:\/\/www.linkedin.com\/in\/sarah-saleh-8a777b176\/\"  class=\"social-link\"><i class=\"flaticon-linkedin\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><\/div><\/div>      \n            <\/div>\n                        <div class=\"edubin-col-xs-12 edubin-col-sm-6 edubin-col-md-6 edubin-col-lg-6\" >\n\n                    <div class=\"edubin-single-teacher text-center active-social\"><div class=\"teacher-image-wrap\"><a href=\"\" ><div class=\"teacher-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder.png\" class=\"attachment-full size-full wp-image-1065\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder.png 1200w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-300x300.png 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-100x100.png 100w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-600x600.png 600w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-1024x1024.png 1024w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-150x150.png 150w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-768x768.png 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-12x12.png 12w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div><\/a><\/div><div class=\"teacher-content-area\"><div class=\"teacher-content\"><a href=\"\" ><h6 class=\"teacher-name\">Monika Weber<\/h6><\/a><span class=\"teacher-degree\">Formateur Agr\u00e9\u00e9<\/span><div class=\"teacher-social\"><a href=\"https:\/\/www.linkedin.com\/in\/monika-weber-822b0a16\/\"  class=\"social-link\"><i class=\"flaticon-linkedin\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><\/div><\/div>      \n            <\/div>\n                        <div class=\"edubin-col-xs-12 edubin-col-sm-6 edubin-col-md-6 edubin-col-lg-6\" >\n\n                    <div class=\"edubin-single-teacher text-center active-social\"><div class=\"teacher-image-wrap\"><a href=\"\" ><div class=\"teacher-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder.png\" class=\"attachment-full size-full wp-image-1065\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder.png 1200w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-300x300.png 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-100x100.png 100w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-600x600.png 600w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-1024x1024.png 1024w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-150x150.png 150w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-768x768.png 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-12x12.png 12w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div><\/a><\/div><div class=\"teacher-content-area\"><div class=\"teacher-content\"><a href=\"\" ><h6 class=\"teacher-name\">James Dennison<\/h6><\/a><span class=\"teacher-degree\">Formateur Agr\u00e9\u00e9<\/span><div class=\"teacher-social\"><a href=\"https:\/\/www.linkedin.com\/in\/james-dennison-47147752\/\"  class=\"social-link\"><i class=\"flaticon-linkedin\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><\/div><\/div>      \n            <\/div>\n                        <div class=\"edubin-col-xs-12 edubin-col-sm-6 edubin-col-md-6 edubin-col-lg-6\" >\n\n                    <div class=\"edubin-single-teacher text-center active-social\"><div class=\"teacher-image-wrap\"><a href=\"\" ><div class=\"teacher-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder.png\" class=\"attachment-full size-full wp-image-1065\" alt=\"\" srcset=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder.png 1200w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-300x300.png 300w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-100x100.png 100w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-600x600.png 600w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-1024x1024.png 1024w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-150x150.png 150w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-768x768.png 768w, https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/woocommerce-placeholder-12x12.png 12w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div><\/a><\/div><div class=\"teacher-content-area\"><div class=\"teacher-content\"><a href=\"\" ><h6 class=\"teacher-name\">Giovanni Esposito<\/h6><\/a><span class=\"teacher-degree\">Formateur Agr\u00e9\u00e9<\/span><div class=\"teacher-social\"><a href=\"https:\/\/www.linkedin.com\/in\/giovanni-esposito-36b39383\/\"  class=\"social-link\"><i class=\"flaticon-linkedin\" aria-hidden=\"true\"><\/i><\/a><\/div><\/div><\/div><\/div>      \n            <\/div>\n        \n    <\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1803558 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1803558\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-86f7e9c\" data-id=\"86f7e9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b88c2e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b88c2e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-496022e elementor-invisible\" data-id=\"496022e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf17869 edubin-title-align-center elementor-invisible elementor-widget elementor-widget-section-title-addons\" data-id=\"bf17869\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;zoomIn&quot;}\" data-widget_type=\"section-title-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"edubin-section-title edubin-subtitle-position-top title-style-four\">\r\n                <h2 class=\"section-title-txt\">Questions fr\u00e9quemment pos\u00e9es\n<\/h2><div class=\"edubin-title-sperator-sec\"><span class=\"edubin-title-sperator\">&nbsp;<\/span><\/div><p class=\"section-subtitle-txt\">Qui nous sommes<\/p>            <\/div>\r\n\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8132bee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8132bee\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ed4033a elementor-invisible\" data-id=\"ed4033a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0d949ac elementor-widget elementor-widget-accordion\" data-id=\"0d949ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1421\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1421\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">L'institut de formation MCP Med est-il un \u00e9tablissement de formation agr\u00e9\u00e9 ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1421\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1421\"><p>Oui. MCP Med Training Institute est un \u00e9tablissement de formation agr\u00e9\u00e9 par la Malta Further and Higher Education Authority, num\u00e9ro de licence : 2021-016.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1422\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1422\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Quel type d'\u00e9tablissement d'enseignement est l'Institut de formation MCP ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1422\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1422\"><p>L'Institut de formation MCP Med est un centre d'excellence en mati\u00e8re d'enseignement et de formation professionnels (EFP) qui propose des formations sur mesure aux acteurs de la migration.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1423\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1423\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Les cours propos\u00e9s par l'institut de formation MCP Med sont-ils accr\u00e9dit\u00e9s ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1423\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1423\"><p>La plupart des cours du MCP Med Training Institute sont accr\u00e9dit\u00e9s par la Malta Further and Higher Education Authority (MFHEA) et offrent aux \u00e9tudiants des cr\u00e9dits acad\u00e9miques enti\u00e8rement transf\u00e9rables (ECTS).<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fc623c3 elementor-invisible\" data-id=\"fc623c3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a9b992b elementor-widget elementor-widget-accordion\" data-id=\"a9b992b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1771\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1771\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Qui peut s'inscrire aux cours de l'Institut de formation MCP Med ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1771\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1771\"><p>La participation aux cours de l'Institut de formation MCP Med se fait sur la base de nominations, les candidats \u00e9tant officiellement d\u00e9sign\u00e9s par leurs institutions, organisations ou autorit\u00e9s publiques comp\u00e9tentes respectives. Les candidatures directes de particuliers ne sont pas accept\u00e9es pour le moment. Pour plus d'informations, veuillez contacter <a href=\"mailto:mcpmedti@icmpd.org\" target=\"_blank\" rel=\"noopener\">mcpmedti@icmpd.org<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1772\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1772\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Qui sont les formateurs agr\u00e9\u00e9s de l'Institut de formation MCP Med ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1772\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1772\"><p>Les formateurs agr\u00e9\u00e9s sont approuv\u00e9s par l'Institut de formation MCP Med pour dispenser des programmes de formation particuliers en son nom, sur la base de leurs qualifications p\u00e9dagogiques et th\u00e9matiques.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1773\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1773\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Comment les cours sont-ils donn\u00e9s ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1773\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1773\"><p>Les m\u00e9thodes d'enseignement de l'Institut de formation MCP Med sont synchrones, asynchrones et mixtes. Nous investissons dans des solutions technologiques pour dispenser des cours en fonction des besoins de nos partenaires.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1774\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1774\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-chevron-down\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Qui d\u00e9cide de ce que fait l'institut de formation MCP Med ?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1774\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1774\"><p>Dirig\u00e9 par un conseil d'administration compos\u00e9 de pays partenaires du Sud (CPS), de donateurs et de l'ICMPD, qui disposent tous d'un droit de vote \u00e9gal, il d\u00e9cide des activit\u00e9s de l'Institut de formation m\u00e9dicale MCP.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Bienvenue au MCP MEDTraining Institute Qui sommes-nous L'Institut de formation sur le partenariat de capacit\u00e9 en mati\u00e8re de migration pour la M\u00e9diterran\u00e9e (MCP Med Training Institute) est un centre d'excellence professionnelle sp\u00e9cifiquement d\u00e9di\u00e9 \u00e0 la gouvernance des migrations, un projet mis en \u0153uvre par l'ICMPD. Il s'agit d'un fournisseur de formation trans-th\u00e9matique pour les \u00c9tats m\u00e9diterran\u00e9ens partenaires du sud de l'UE. Situ\u00e9 \u00e0 Malte, il offre...<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-774","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.3 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Home - MCP Med TI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home\" \/>\n<meta property=\"og:description\" content=\"Welcome to MCP MEDTraining Institute Who We Are &nbsp; The Training Institute on Migration Capacity Partnership for the Mediterranean (MCP Med Training Institute) is a Centre of Vocational Excellence specifically for migration governance, a project implemented by ICMPD. It is a cross-thematic training provider for non-EU Southern Partner Mediterranean states. Situated in Malta, it boasts&#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mcpmed-ti.edu.eu\/fr\/\" \/>\n<meta property=\"og:site_name\" content=\"MCP Med TI\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-03T13:50:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2019\/08\/034-ebook.png\" \/>\n\t<meta property=\"og:image:width\" content=\"256\" \/>\n\t<meta property=\"og:image:height\" content=\"256\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/\",\"name\":\"Home - MCP Med TI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/034-ebook.png\",\"datePublished\":\"2019-04-05T05:26:19+00:00\",\"dateModified\":\"2026-08-03T13:50:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/034-ebook.png\",\"contentUrl\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/034-ebook.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#website\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/\",\"name\":\"MCP Med TI\",\"description\":\"MCP Med TI\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#organization\",\"name\":\"MCP Med Training Institute\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-cropped-256px_MCPMedTI-1.png\",\"contentUrl\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-cropped-256px_MCPMedTI-1.png\",\"width\":512,\"height\":512,\"caption\":\"MCP Med Training Institute\"},\"image\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/linkedin.com\\\/company\\\/mcpmedti\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Accueil - MCP Med TI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mcpmed-ti.edu.eu\/fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Home","og_description":"Welcome to MCP MEDTraining Institute Who We Are &nbsp; The Training Institute on Migration Capacity Partnership for the Mediterranean (MCP Med Training Institute) is a Centre of Vocational Excellence specifically for migration governance, a project implemented by ICMPD. It is a cross-thematic training provider for non-EU Southern Partner Mediterranean states. Situated in Malta, it boasts&#8230;","og_url":"https:\/\/mcpmed-ti.edu.eu\/fr\/","og_site_name":"MCP Med TI","article_modified_time":"2026-08-03T13:50:41+00:00","og_image":[{"width":256,"height":256,"url":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2019\/08\/034-ebook.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mcpmed-ti.edu.eu\/","url":"https:\/\/mcpmed-ti.edu.eu\/","name":"Accueil - MCP Med TI","isPartOf":{"@id":"https:\/\/mcpmed-ti.edu.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mcpmed-ti.edu.eu\/#primaryimage"},"image":{"@id":"https:\/\/mcpmed-ti.edu.eu\/#primaryimage"},"thumbnailUrl":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2019\/08\/034-ebook.png","datePublished":"2019-04-05T05:26:19+00:00","dateModified":"2026-08-03T13:50:41+00:00","breadcrumb":{"@id":"https:\/\/mcpmed-ti.edu.eu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mcpmed-ti.edu.eu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mcpmed-ti.edu.eu\/#primaryimage","url":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2019\/08\/034-ebook.png","contentUrl":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2019\/08\/034-ebook.png"},{"@type":"BreadcrumbList","@id":"https:\/\/mcpmed-ti.edu.eu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mcpmed-ti.edu.eu\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/mcpmed-ti.edu.eu\/#website","url":"https:\/\/mcpmed-ti.edu.eu\/","name":"MCP Med TI","description":"MCP Med TI","publisher":{"@id":"https:\/\/mcpmed-ti.edu.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mcpmed-ti.edu.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mcpmed-ti.edu.eu\/#organization","name":"Institut de formation m\u00e9dicale MCP","url":"https:\/\/mcpmed-ti.edu.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mcpmed-ti.edu.eu\/#\/schema\/logo\/image\/","url":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI-1.png","contentUrl":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI-1.png","width":512,"height":512,"caption":"MCP Med Training Institute"},"image":{"@id":"https:\/\/mcpmed-ti.edu.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/linkedin.com\/company\/mcpmedti"]}]}},"_links":{"self":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/pages\/774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/comments?post=774"}],"version-history":[{"count":926,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/pages\/774\/revisions"}],"predecessor-version":[{"id":20341,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/pages\/774\/revisions\/20341"}],"wp:attachment":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/media?parent=774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}