{"id":996,"date":"2022-04-12T11:14:18","date_gmt":"2022-04-12T11:14:18","guid":{"rendered":"https:\/\/mcpmed-ti.edu.eu\/?page_id=996"},"modified":"2025-03-07T08:42:02","modified_gmt":"2025-03-07T07:42:02","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/mcpmed-ti.edu.eu\/fr\/privacy-policy\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"<h2 class=\"wp-block-heading\" id=\"h-who-we-are\">Qui sommes-nous ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">L'adresse de notre site web est la suivante : https:\/\/mcpmed-ti.edu.eu.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-comments\">Commentaires<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque les visiteurs laissent des commentaires sur le site web, nous recueillons les donn\u00e9es figurant dans le formulaire de commentaires, ainsi que l'adresse IP du visiteur et la cha\u00eene de l'agent utilisateur du navigateur afin de faciliter la d\u00e9tection des spams.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une cha\u00eene anonyme cr\u00e9\u00e9e \u00e0 partir de votre adresse \u00e9lectronique (\u00e9galement appel\u00e9e \"hash\") peut \u00eatre fournie au service Gravatar pour v\u00e9rifier si vous l'utilisez. La politique de confidentialit\u00e9 du service Gravatar est disponible ici : https:\/\/automattic.com\/privacy\/. Apr\u00e8s approbation de votre commentaire, votre photo de profil est visible par le public dans le contexte de votre commentaire.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-media\">M\u00e9dias<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous t\u00e9l\u00e9chargez des images sur le site web, vous devez \u00e9viter de t\u00e9l\u00e9charger des images contenant des donn\u00e9es de localisation int\u00e9gr\u00e9es (EXIF GPS). Les visiteurs du site web peuvent t\u00e9l\u00e9charger et extraire toutes les donn\u00e9es de localisation des images sur le site web.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-cookies\">Cookies<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous laissez un commentaire sur notre site web, vous pouvez choisir d'enregistrer votre nom, votre adresse \u00e9lectronique et votre site web dans des cookies. Ces cookies sont destin\u00e9s \u00e0 vous faciliter la t\u00e2che, de sorte que vous n'ayez pas \u00e0 fournir \u00e0 nouveau vos coordonn\u00e9es lorsque vous laissez un autre commentaire. Ces cookies ont une dur\u00e9e de vie d'un an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous visitez notre page de connexion, nous installerons un cookie temporaire pour d\u00e9terminer si votre navigateur accepte les cookies. Ce cookie ne contient aucune donn\u00e9e personnelle et est supprim\u00e9 lorsque vous fermez votre navigateur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous vous connectez, nous installons \u00e9galement plusieurs cookies pour enregistrer vos informations de connexion et vos choix d'affichage \u00e0 l'\u00e9cran. Les cookies de connexion ont une dur\u00e9e de vie de deux jours et les cookies d'options d'\u00e9cran ont une dur\u00e9e de vie d'un an. Si vous s\u00e9lectionnez l'option \u201cSe souvenir de moi\u201d, votre connexion sera conserv\u00e9e pendant deux semaines. Si vous vous d\u00e9connectez de votre compte, les cookies de connexion seront supprim\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous modifiez ou publiez un article, un cookie suppl\u00e9mentaire sera enregistr\u00e9 dans votre navigateur. Ce cookie ne contient aucune donn\u00e9e personnelle et indique simplement l'identifiant de l'article que vous venez de modifier. Il expire au bout d'un jour.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-embedded-content-from-other-websites\">Contenu int\u00e9gr\u00e9 d'autres sites web<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les articles de ce site web peuvent contenir du contenu int\u00e9gr\u00e9 (par exemple des vid\u00e9os, des images, des articles, etc.). Le contenu int\u00e9gr\u00e9 provenant d'autres sites web se comporte exactement de la m\u00eame mani\u00e8re que si le visiteur avait visit\u00e9 l'autre site web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces sites web peuvent collecter des donn\u00e9es vous concernant, utiliser des cookies, int\u00e9grer un suivi suppl\u00e9mentaire par des tiers et surveiller votre interaction avec ce contenu int\u00e9gr\u00e9, y compris votre interaction avec le contenu int\u00e9gr\u00e9 si vous avez un compte et que vous \u00eates connect\u00e9 \u00e0 ce site web.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-who-we-share-your-data-with\">Avec qui partageons-nous vos donn\u00e9es ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous demandez une r\u00e9initialisation de votre mot de passe, votre adresse IP sera incluse dans l'e-mail de r\u00e9initialisation.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-how-long-do-we-retain-your-data\">Combien de temps conservons-nous vos donn\u00e9es ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous laissez un commentaire, celui-ci et ses m\u00e9tadonn\u00e9es sont conserv\u00e9s ind\u00e9finiment. Cela nous permet de reconna\u00eetre et d'approuver automatiquement les commentaires ult\u00e9rieurs au lieu de les conserver dans une file d'attente de mod\u00e9ration.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour les utilisateurs qui s'inscrivent sur notre site web (le cas \u00e9ch\u00e9ant), nous stockons \u00e9galement les informations personnelles qu'ils fournissent dans leur profil d'utilisateur. Tous les utilisateurs peuvent consulter, modifier ou supprimer leurs informations personnelles \u00e0 tout moment, mais ils ne peuvent pas changer leur nom d'utilisateur. Les administrateurs du site web peuvent \u00e9galement consulter et modifier ces informations.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-what-rights-do-you-have-over-your-data\">Quels sont vos droits sur vos donn\u00e9es ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous avez un compte sur ce site web, ou si vous avez laiss\u00e9 des commentaires, vous pouvez demander \u00e0 recevoir un fichier export\u00e9 des donn\u00e9es personnelles que nous d\u00e9tenons \u00e0 votre sujet, y compris toutes les donn\u00e9es que vous nous avez fournies. Vous pouvez \u00e9galement nous demander d'effacer toutes les donn\u00e9es \u00e0 caract\u00e8re personnel que nous d\u00e9tenons \u00e0 votre sujet. Cela n'inclut pas les donn\u00e9es que nous sommes oblig\u00e9s de conserver \u00e0 des fins administratives, juridiques ou de s\u00e9curit\u00e9.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-where-we-send-your-data-to\">O\u00f9 envoyons-nous vos donn\u00e9es ?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Les commentaires des visiteurs peuvent \u00eatre v\u00e9rifi\u00e9s par un service automatis\u00e9 de d\u00e9tection des spams.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour plus d'informations sur la protection des donn\u00e9es au sein de l'Union europ\u00e9enne, veuillez consulter <a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/EN\/TXT\/?uri=uriserv:OJ.L_.2016.119.01.0001.01.ENG\">R\u00e8glement (UE) 2016\/679<\/a>, R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD).<\/p>","protected":false},"excerpt":{"rendered":"<p>Who we are Our website address is: https:\/\/mcpmed-ti.edu.eu. Comments When visitors leave comments on the website we collect the data shown in the comments form, and also the visitor\u2019s IP address and browser user agent string to help spam detection. An anonymized string created from your email address (also called a hash) may be provided&#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-996","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Privacy Policy - MCP Med TI<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mcpmed-ti.edu.eu\/fr\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy\" \/>\n<meta property=\"og:description\" content=\"Who we are Our website address is: https:\/\/mcpmed-ti.edu.eu. Comments When visitors leave comments on the website we collect the data shown in the comments form, and also the visitor\u2019s IP address and browser user agent string to help spam detection. An anonymized string created from your email address (also called a hash) may be provided&#8230;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mcpmed-ti.edu.eu\/fr\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"MCP Med TI\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-07T07:42:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy - MCP Med TI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#website\"},\"datePublished\":\"2022-04-12T11:14:18+00:00\",\"dateModified\":\"2025-03-07T07:42:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#website\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/\",\"name\":\"MCP Med TI\",\"description\":\"MCP Med TI\",\"publisher\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#organization\",\"name\":\"MCP Med Training Institute\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-cropped-256px_MCPMedTI-1.png\",\"contentUrl\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/cropped-cropped-256px_MCPMedTI-1.png\",\"width\":512,\"height\":512,\"caption\":\"MCP Med Training Institute\"},\"image\":{\"@id\":\"https:\\\/\\\/mcpmed-ti.edu.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/linkedin.com\\\/company\\\/mcpmedti\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Privacy Policy - MCP Med TI","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mcpmed-ti.edu.eu\/fr\/privacy-policy\/","og_locale":"fr_FR","og_type":"article","og_title":"Privacy Policy","og_description":"Who we are Our website address is: https:\/\/mcpmed-ti.edu.eu. Comments When visitors leave comments on the website we collect the data shown in the comments form, and also the visitor\u2019s IP address and browser user agent string to help spam detection. An anonymized string created from your email address (also called a hash) may be provided&#8230;","og_url":"https:\/\/mcpmed-ti.edu.eu\/fr\/privacy-policy\/","og_site_name":"MCP Med TI","article_modified_time":"2025-03-07T07:42:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mcpmed-ti.edu.eu\/privacy-policy\/","url":"https:\/\/mcpmed-ti.edu.eu\/privacy-policy\/","name":"Privacy Policy - MCP Med TI","isPartOf":{"@id":"https:\/\/mcpmed-ti.edu.eu\/#website"},"datePublished":"2022-04-12T11:14:18+00:00","dateModified":"2025-03-07T07:42:02+00:00","breadcrumb":{"@id":"https:\/\/mcpmed-ti.edu.eu\/privacy-policy\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mcpmed-ti.edu.eu\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/mcpmed-ti.edu.eu\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mcpmed-ti.edu.eu\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy"}]},{"@type":"WebSite","@id":"https:\/\/mcpmed-ti.edu.eu\/#website","url":"https:\/\/mcpmed-ti.edu.eu\/","name":"MCP Med TI","description":"MCP Med TI","publisher":{"@id":"https:\/\/mcpmed-ti.edu.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mcpmed-ti.edu.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mcpmed-ti.edu.eu\/#organization","name":"Institut de formation m\u00e9dicale MCP","url":"https:\/\/mcpmed-ti.edu.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mcpmed-ti.edu.eu\/#\/schema\/logo\/image\/","url":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI-1.png","contentUrl":"https:\/\/mcpmed-ti.edu.eu\/wp-content\/uploads\/2022\/04\/cropped-cropped-256px_MCPMedTI-1.png","width":512,"height":512,"caption":"MCP Med Training Institute"},"image":{"@id":"https:\/\/mcpmed-ti.edu.eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/linkedin.com\/company\/mcpmedti"]}]}},"_links":{"self":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/pages\/996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/comments?post=996"}],"version-history":[{"count":2,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/pages\/996\/revisions"}],"predecessor-version":[{"id":2433,"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/pages\/996\/revisions\/2433"}],"wp:attachment":[{"href":"https:\/\/mcpmed-ti.edu.eu\/fr\/wp-json\/wp\/v2\/media?parent=996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}